{"id":85,"date":"2007-03-01T17:24:00","date_gmt":"2007-03-01T17:24:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=85"},"modified":"2007-03-01T17:24:00","modified_gmt":"2007-03-01T17:24:00","slug":"un-problema-grave","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2007\/03\/01\/un-problema-grave\/","title":{"rendered":"Un problema grave."},"content":{"rendered":"<p>Cuatro de la tarde, hora keniata (la hora zul\u00fa perdi\u00f3 mucho desde lo de Lauren Postigo). Cubil de los Servidores Rugientes.<br \/>Suena el tel\u00e9fono.<br \/>-Sistemas, buenas tardes, \u00bfen qu\u00e9 puedo fustigarte?<br \/>-Hooola Wardog, mira, que estoy hasta los huevos del Outlook Express este.<br \/>Es Charly, del Indomable Departamento de Exportaci\u00f3n.<br \/>-\u00bfQu\u00e9 le pasa?<br \/>-Que me dice que no tengo memoria.<br \/>-\u00bfY es verdad?<br \/>-\u00bfEl qu\u00e9?<br \/>-Que no tienes memoria.<br \/>-Y yo que s\u00e9.<br \/>-Bueno, vamos a hacer la prueba. \u00bfQu\u00e9 cenaste anoche?<br \/>-Pues&#8230; Puesssss&#8230;No me acuerdo.<br \/>-En efecto, no tienes memoria. Pero volviendo al tema del Outlook, \u00bfqu\u00e9 te pasa?<br \/>-Que no lo puedo abrir, me sale un error y se me bloquea el ordenador.<br \/>-Veamos&#8230;<br \/>Examino la carpeta de almacenamiento de correo y ah\u00ed est\u00e1. M\u00e1s de 2GB de correo. Eso es t\u00f3xico para Outlook.<br \/>-Fale, t\u00edo, mira te voy a cambiar ese gestor de correo por el Thunderbird y dejar\u00e1s de tener ese problema.<br \/>Fij\u00e1os c\u00f3mo de vez en cuando ayudo a la gente, les arreglo las cosas y tal. Le instalao el Thunderbird y cuando se pone a importar los correos, coge y se cuelga el PC.  Hala, me toca ir al Indomable Departamento de Exportaci\u00f3n.<br \/>Llego y en el monitor se lee, con letras blancas sobre fondo azul: \u00abNo se ha podido escribir en el disco C:. Probablemente los datos se hayan perdido en el espacio interestelar o algo\u00bb<br \/>Cojonudo. BSOD. Reset.<br \/>\u00a1BIP!\u00a1BIP!<br \/>\u00abPrimary Hard Disk Fail\u00bb<br \/>\u00a1Jostia!\u00a1El disco se ha jodido!<br \/>-\u00a1Ah! \u00a1Y eso me sale tambi\u00e9n de vez en cuando!<br \/>Amos, no me jodas. Que esto me lo dice Lucky y vale, de acuerdo. Pero un t\u00edo que se pasa el d\u00eda hablando ingl\u00e9s y que no entienda un mensaje de error de ese tipo&#8230;<br \/>-Trad\u00faceme el mensaje, porfa, que yo de ingl\u00e9s no ando muy ducho.<br \/>-\u00abFallo del disco primario\u00bb &#8211; Me dice ufano y sonriente.<br \/>-Aham. Pues eso es grave. \u00bfSabes qu\u00e9 quiere decir?<br \/>-Mmm&#8230;Pues que el disco principal est\u00e1 fallando.<br \/>-\u00a1Muy bien!\u00bfY sabes cu\u00e1l es el disco principal?\u00bfEh?\u00bfLo sabes?<br \/>Se rasca.<br \/>-Pueees&#8230; \u00bfel disco duro?<br \/>-Exacto. \u00bfY sabes qui\u00e9n va a perder toooodos los ficheros que no haya guardado en el servidor?<br \/>-\u00a1No jodas!\u00a1Arreglalo!\u00a1Arreglalo!<br \/>-Imposible, macho. Te cambio el disco duro y te reinstalo todo, pero vamos, que lo que no hayas guardado en el servidor de ofim\u00e1tica&#8230;<br \/>-Joder, t\u00edo, que no hab\u00eda guardado nada. Que est\u00e1 todo ah\u00ed.<br \/>Respiro hondo. Me crujo el cuello, relajo la espalda y miro su cara p\u00e1lida y llorosa. Pobrecillo.<br \/>-Pues te jodes.<br \/>Del alma me sali\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro de la tarde, hora keniata (la hora zul\u00fa perdi\u00f3 mucho desde lo de Lauren Postigo). Cubil de los Servidores Rugientes.Suena el tel\u00e9fono.-Sistemas, buenas tardes, \u00bfen qu\u00e9 puedo fustigarte?-Hooola Wardog, mira, que estoy hasta los huevos del Outlook Express este.Es Charly, del Indomable Departamento de Exportaci\u00f3n.-\u00bfQu\u00e9 le pasa?-Que me dice que no tengo memoria.-\u00bfY es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-85","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/85\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=85"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=85"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}