{"id":413,"date":"2010-07-08T14:52:52","date_gmt":"2010-07-08T13:52:52","guid":{"rendered":"http:\/\/mundowdg.com\/blog\/?p=413"},"modified":"2013-01-28T00:35:38","modified_gmt":"2013-01-28T00:35:38","slug":"atila","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2010\/07\/08\/atila\/","title":{"rendered":"Atila"},"content":{"rendered":"<p>Atila lleva poco tiempo en la oficina. Le han puesto en recepci\u00f3n de pedidos. Es un puesto que siempre ocupan los novatos porque se supone que no tiene m\u00e1s complejidad que elegir el cliente, serie de pedido y meter las cosas que haya solicitado nuestro cliente. Y de hecho, la aplicaci\u00f3n no permite muchas m\u00e1s cosas.<\/p>\n<p>Durante un tiempo, nuestro buen hombre, un t\u00edo grande y rudo, con voz grave, gafap\u00e1stico perdido \u00a0(de color verde); con los brazos peludos como la pata de un oso y, por supuesto, el cerebro del tama\u00f1o de los test\u00edculos de una mosca del vinagre hembra; pas\u00f3 desapercibido excepto en el comedor, donde trasegaba ingentes cantidades de comida. MKII y yo no habl\u00e1bamos de \u00e9l m\u00e1s que para calcular cu\u00e1ndo deber\u00eda terminar la digesti\u00f3n en funci\u00f3n de la composici\u00f3n de su comida para evitar ir al ba\u00f1o en las dos horas posteriores al evento, que calcul\u00e1bamos inhumano y ciertas fuentes califican como \u00abolor a cad\u00e1ver de pol\u00edtico espa\u00f1ol enterrado en esti\u00e9rcol de banquero fermentado\u00bb.<\/p>\n<p>Pero un buen d\u00eda, Atila encontr\u00f3 el tel\u00e9fono en su mesa. Y otro buen d\u00eda, averigu\u00f3 que en \u00absistemas\u00bb cog\u00edan el tel\u00e9fono los inform\u00e1ticos. O tal vez no fue un buen d\u00eda. Para \u00e9l.<\/p>\n<p>\u00a1Bimbambidubi! \u00a1Dubi!<\/p>\n<p>-Sistemas, la oferta de hoy es un gotohell poco hecho con patata asada. \u00bfQu\u00e9 desea?<br \/>\n-Ehto&#8230; \u00bfno eh ah\u00ed loh inform\u00e1ticoj?<br \/>\n-S\u00ed se\u00f1or, aqu\u00ed estamos. Wardog al aparato.- como no me suena la voz ni el acento berraquil, pues seamos amables.<br \/>\n-Ah. Pueh mira mi pantalla que \u00a0ehto eh una mierda.<br \/>\n-Bien, bien&#8230;<br \/>\n-\u00bfYa la veh? \u00bfEh? \u00a1La vej o no la vej! &#8211; impaciente, maleducado y bestia. Este se ha criado entre jabal\u00edes.<br \/>\n-Pues es que no puedo, oye.<br \/>\n-Pueh vaya inform\u00e1tico. Po&#8217; ven p&#8217;ac\u00e1.<br \/>\n-Tampoco puedo.<br \/>\n-Pueh aqu\u00ed me planto y cuando me digan que qu\u00e9 cohonej ejtoy haciendo, digo que el puto inform\u00e1tico no me hace caso.<br \/>\n-T\u00fa mismo.<\/p>\n<p>Clic. Que me gusta a m\u00ed que llamen y no diga ni qui\u00e9n es, ni d\u00f3nde est\u00e1 y que por supuesto, no use el portal de soporte. \u00bfPa qu\u00e9?<\/p>\n<p>\u00a1Bimbambidubi! \u00a1Dubi!<\/p>\n<p>-Sistemas, para hablar con un humano, pulse uno, para hablar con algo inhumano, cuelgue y mantenga una conversaci\u00f3n mental.<br \/>\n-\u00bfWardog?<br \/>\n-Servidor. Es que estaba grabando unas cosillas para el contestador.<br \/>\n-Ah, mira, que soy el supervisor de recepci\u00f3n de pedidos. Tengo a Atila parado porque dice que no le haces caso.<br \/>\n-Ah, que se llama Atila-. Al fin relaciono la voz con el engendro.- No, si ha llamado antes, pero no ha dicho ni su nombre, ni departamento ni equipo, as\u00ed que poco puedo hacer hablando con un desconocido.<br \/>\n-Anda co\u00f1o.<br \/>\n-Camina, pene.<br \/>\n-Va. Te lo paso. Puesto 173.<\/p>\n<p>Conectando a puesto 173&#8230;<\/p>\n<p>-\u00a1Oye!<br \/>\n-Co\u00f1o, t\u00fa, qu\u00e9 susto. Ten cuidado, que soy una persona fr\u00e1gil y asustadiza. Atila, \u00bfno?<br \/>\n-J\u00ed. \u00a0Que ehto eh una mierda.<br \/>\n-Pues no lo toques por si pringa. \u00bfAlg\u00fan problema con el ordenador?<br \/>\n-\u00a1Poh no tejtoy \u00a0diciendo que ehto eh una mierda!<br \/>\n-Ya, pero es que para esos asuntos tienes que hablar con estercoleros y has llamado a sistemas, as\u00ed que s\u00f3lo arreglamos problemas con ordenadores.<br \/>\n-Pueh eso tejtoy diciendo, joder. Que el o r d e n a d o r &#8211; dice muy despacio y con recochineo &#8211; ehte eh una mierda y no puedo trabajar con \u00e9l. Tr\u00e1eme otro.<\/p>\n<p>Oh. Ah. Este t\u00edo me recuerda alguien. Y no es por el acento. Y no es por el tono de voz. Este t\u00edo es Pollamboca sin tetas.<\/p>\n<p>-No. Para la mierda de trabajo que haces, te sobra con el que tienes.<br \/>\n-Oye t\u00fa, cuida\u00edto conmigo, \u00bfeh?<br \/>\n-Lo mismo te digo. \u00a0Te conviene que nos llevemos bien. Ya sin co\u00f1as. \u00bfQu\u00e9 cojones te pasa?<br \/>\n-Que me ha desaparecido la barra de la derecha. &#8211; Le tengo cabreado. Pobre.<br \/>\n-Um&#8230; vaya. El t\u00edpico caso de la desaparici\u00f3n de elementos con nombre poco conciso&#8230; \u00bfQu\u00e9 barra?<br \/>\n-La de la derecha.- Esto va a ser largo.<br \/>\n-Vale. \u00bfC\u00f3mo \u00a0era la barra?<br \/>\n-Pueh grij, como todas. &#8211; Muy largo.<br \/>\n-No, que qu\u00e9 hac\u00eda esa barra.<br \/>\n-\u00bfY tu ereh inform\u00e1tico? \u00bfPos qu\u00e9 va a hacer? \u00a1Subir y bajar las cosas!<br \/>\n-Ah, que no es una barra de herramientas, que es una barra de desplazamiento. Vale, vale. \u00bfY de qu\u00e9 puto programa te ha desaparecido?<br \/>\n-\u00a1Yo que s\u00e9 c\u00f3mo se llama esto!<br \/>\n-Pues vaya puta mierda de auxiliar administrativo que no sabe c\u00f3mo se llaman sus herramientas.<br \/>\n-Oye, sin faltar, \u00bfeh? Que se lo digo a mi supervisor.<br \/>\n-No, si te est\u00e1 oyendo, y seguro que se est\u00e1 preguntando por qu\u00e9 sigues vivo a estas alturas. Especifica o cuelga.<br \/>\n-Mfgrs&#8230;. pues&#8230; El programa este que entras en internet y te mete los pedidos.<br \/>\n-Um&#8230; ya veo por qu\u00e9 tanta urgencia&#8230; te quieres meter los pedidos&#8230; bien. Entra en el programa ese y ens\u00e9\u00f1ame d\u00f3nde se ha ca\u00eddo la barra.<br \/>\n-Entra t\u00fa.<br \/>\n-No, que me da la risa. Vamos, que la vida pasa, machote.<br \/>\n-Anda que no sois comodones los inform\u00e1ticos, \u00bfeh?<br \/>\n-Te quedan dos. No es comodidad, es que nos gusta ver d\u00f3nde co\u00f1o met\u00e9is la pata, para poder ir a por la mula tractora y sacaros de la mierda.<br \/>\n-Mfrgsls&#8230;.- gru\u00f1e durante un rato y se dispone a abrir el programa que trasnfiere los pedidos desde el buz\u00f3n EDI al ERP.- Ehto no va.<br \/>\n-Tienes que poner el nombre de usuario y la contrase\u00f1a.<br \/>\n-No me lo s\u00e9.<br \/>\n-\u00bfY c\u00f3mo has entrado antes?<br \/>\n-Me entra un compa\u00f1ero.<br \/>\n-Y los comodones somos nosotros. En el manual lo tienes, es el mismo para todos.<br \/>\n-\u00bfY d\u00f3nde eht\u00e1 el manual ese?<br \/>\n-T\u00fa sabr\u00e1s, macho, en alg\u00fan caj\u00f3n, supongo.<br \/>\n-\u00bfEn el de arriba o en el de abajo?<br \/>\n-Ver\u00e1s, Atila, como soy inform\u00e1tico, tengo las dotes adivinatorias hiperdesarrolladas. En el de arriba.<br \/>\n-\u00a1Co\u00f1o! \u00a1Aquijt\u00e1! \u00a1Anda que no hay libricos aqu\u00ed! \u00bfY c\u00f3mo lo has sabido?<br \/>\n-F\u00e1cil. Sois todos tan perros que no os agach\u00e1is veinte cent\u00edmetros voluntariamente ni queriendo.<br \/>\n-Ah, pero en ehte manual no vi\u00e9 n\u00e1 del pograma, n\u00e1 mah que de la cafetera. Hablar con vosotroh es como cagar p\u00e1rriba.<br \/>\n-Una. Vale, no sabes identificar el manual apropiado. Te mando el manual al correo, no sea que te reviente una meninge y la tengamos. Ea. Revisa el correo.<\/p>\n<p>Mientras el se\u00f1or Atila busca el iconito para acceder al correo, accedo a su escritorio y lo quito. As\u00ed, por vicio.<\/p>\n<p>-\u00a1Wardog! \u00a1Que no puedo entrar en el correo!<br \/>\n-Chico, eres una mina. \u00bfPor qu\u00e9 no puedes entrar?<br \/>\n-\u00a1Porque no tengo el programa!<br \/>\n-\u00bfC\u00f3mo no lo vas a tener?<br \/>\n-Que te lo digo yo que no lo tengo, joder, que ha desaparec\u00edo&#8230;<br \/>\n-T\u00edo, \u00bft\u00fa me est\u00e1s vacilando? Llama a tu supervisor. Que se ponga.<br \/>\n-Poj claro que le llamo. Ver\u00e1h t\u00fa.<\/p>\n<p>Espero a que venga el super&#8230;<\/p>\n<p>-\u00bfWardog? \u00bfMe has llamado?<br \/>\n-S\u00ed, que dice Atila que no tiene el gestor de correo- pongo otra vez \u00a0el iconito- m\u00edralo, haz el favor.<br \/>\n-Aqu\u00ed est\u00e1, s\u00ed, no hay problema&#8230;<br \/>\n-Vale, gracias, majo.<\/p>\n<p>De fondo se oye \u00ab\u00a1Cagonlahostia! \u00a1Pero si no estaba!\u00bb<\/p>\n<p>-\u00bfWardog?<br \/>\n-Hola, Atila. En el correo ese te mando la contrase\u00f1a y el usuario para acceder a los pedidos telem\u00e1ticos. Cuando lo veas, s\u00f3lo tienes que copiar y pegar los datos en la web y ya podr\u00e1s entrar. Si te falta la barra esa, me lo dices que yo lo vea. \u00bfVale?<br \/>\n-\u00a1Buuuuuuu! Po anda que no me haj dicho t\u00fa cosah ni naaaaaa&#8230;<br \/>\n-Eso es que vale.<br \/>\n-Wardog, que tengo un problema con el correo este.<br \/>\n-Incre\u00edble. Sorpr\u00e9ndeme.\u00a0se reciben loj correoh?<br \/>\n-En la bandeja de entrada. \u00bfT\u00fa es que no tienes m\u00f3vil ni nada?<br \/>\n-Ah, claro, no, si tiene l\u00f3gica.<br \/>\n-No como otros&#8230;<br \/>\n-Vale. \u00bfY c\u00f3mo s\u00e9 yo cu\u00e1l eh el del manual?<br \/>\n-Lo tuyo es grave. \u00bfHas pensado en leer los asuntos de los mensajes?<br \/>\n-\u00bfEn el m\u00f3vil?<br \/>\n-No, detr\u00e1s de tu escroto.<br \/>\n-Mira que erej borde, t\u00fa. Si no s\u00e9 me tienej que ense\u00f1ar, \u00bfno?<br \/>\n-Si no sabes, no deber\u00edas estar ah\u00ed.<br \/>\n-Pueh no lo veo, hajta que no me lo ejpliquej bien, aqu\u00ed me planto y&#8230;<br \/>\n-Y nada, que ah\u00ed te vas a plantar, macho. Y no olvides dec\u00edrselo a tu supervisor, \u00bfvale?<\/p>\n<p>Este se ha librado por una. Estaba probando una nueva filosof\u00eda de fresa, derivada el BOFH-Zen que adem\u00e1s implica buen rollito hasta tres veces y luego, mala leche desbocada. Pero que no. Que no va a resultar. Lo mejor es la mala leche as\u00ed, a bocajarro y el que se ponga delante que pene.<\/p>\n<p>-MKII, \u00bftienes mucho l\u00edo?<br \/>\n-Hoy no, la verdad.<br \/>\n-Genial, necesito un favorcillo: invest\u00edgame de qui\u00e9n es sobrino Atila, el que est\u00e1 en el puesto 173. Recepci\u00f3n de pedidos.<br \/>\n-\u00a1Marchando una de datooooos!<br \/>\n-Gracias, hombre.<\/p>\n<p>\u00a1Bimbambidubi! \u00a1Dubi!<\/p>\n<p>-Sistemas, hoy, por ser jueves, adoraremos y deglutiremos al Maestro FSM a la carbonara.<br \/>\n-\u00bfLo cualo?<br \/>\n-Co\u00f1o, Atila. \u00bfYa has entrado?<br \/>\n-\u00a1Aqu\u00ed no hay un dios que entre!<br \/>\n-RTFM- le contesto mientras adopto la postura BOFH: pies en la mesa y repatingado en la silla.<br \/>\n-\u00a1Ej que lo inform\u00e1tico no tenei vocaleh o qu\u00e9!<br \/>\n-Tenemos. Pero de hecho, ahora mismo echo de menos poder vocalizar el s\u00edmbolo de admiraci\u00f3n para emitir una negaci\u00f3n avoc\u00e1lica.<br \/>\n-\u00a1Que t\u00edo m\u00e1 raro joder! \u00a1Cuida\u00edto conmigooooo!<br \/>\n-Que si has entrado, digo.<br \/>\n-\u00a1Que no se puede!<br \/>\n-Veamos&#8230;- vuelvo a conectar su pantalla y veo que tiene abierto el documento que explica c\u00f3mo loguearse en la web de los cojones, que ya me dir\u00e1n ustedes, usuario y contrase\u00f1a y c\u00f3mo, pulsando tres botones, se integran los pedidos desde el buz\u00f3n EDI en la aplicaci\u00f3n de la empresa. Aparte del manual, hay catorce ventanas del navegador de internet. Raro.<\/p>\n<p>\u00a1Turut! MKII me dice por mensajer\u00eda que Atila es, al parecer, sobrino del $Hyperboss. Joder. Con raz\u00f3n va tan sobrado. Esto requiere andar con mucho tacto. Recordemos que no hace mucho me dieron permiso para hacer el mal&#8230;<\/p>\n<p>-Vale, Atila. Ens\u00e9\u00f1ame c\u00f3mo lo haces.<br \/>\n-Po como t\u00fa m\u00e1jdicho.<br \/>\n-Ens\u00e9\u00f1amelo.<br \/>\n-No me sale de los cojones.<br \/>\n-Cero.<br \/>\n-\u00bfCero qu\u00e9?<br \/>\n-Que cero. Que acabas de ganar el premio gordo. Que ya est\u00e1 bien. Que si no sabes leer un puto manual te vayas a tomar por culo.<br \/>\n-T\u00fa no sabeh qui\u00e9n soy yo&#8230; pringao. Que t\u00fa no sabeh con qui\u00e9n tehtah jugando loh cuartoh.<br \/>\n-T\u00fa no sabes QU\u00c9 soy yo, amigo. Y ahora, tienes dos opciones: o colaboras, o esta oficina es demasiado peque\u00f1a para los dos.<br \/>\n-\u00bfMejtaj amenazando?- grita en voz alta para que todo el mundo le oiga.<br \/>\n-S\u00ed.<\/p>\n<p>Silencio al otro lado. Tal vez no se esperase esa respuesta. Es normal. La gente que depende de alguien con poder asume que puede hacer uso de ese poder, pero no asume que, para ello, al menos deben tener un m\u00ednimo de competencia para que se les tome en serio.<\/p>\n<p>-A ver- cede por fin- mira, yo selecciono el nombre de usuario aqu\u00ed, en el pedefe. Y ahora abro el navegador y lo pego. \u00bfEso est\u00e1 bien?<br \/>\n-De momento lo est\u00e1s haciendo bien, Atila.- Parece que se redime.<br \/>\n-Y ahora me voy al pedefe otra vez y marco la contrase\u00f1a. Y repito la operaci\u00f3n. Abro el navegador y la pego. &#8211; y lo hace literalmente. Abre un nuevo navegador, le da al marcador del EDI, pone la contrase\u00f1a y le da a aceptar. Y claro, no va.<br \/>\n-\u00bfPero c\u00f3mo se puede ser tan animal? \u00bfD\u00f3nde has estado todo este tiempo? \u00bfEn el subs\u00f3tano de un zulo?<br \/>\n-\u00a1Cuidaito conmigoo! \u00a1Si me lo ha ejplicao aj\u00ed el supervisor!<br \/>\n-Que ya te o\u00ed. A ver, amen\u00e1zame.<br \/>\n-No me hace falta amenazarte, te paso con el supervisor.<br \/>\n-Qu\u00e9 pesao. Venga. P\u00e1same.<br \/>\n-\u00bfWardog?<br \/>\n-Co\u00f1o, qu\u00e9 rapidez.<br \/>\n-\u00bfQu\u00e9 pasa ahora? Atila est\u00e1 rabioso porque dice que no le arreglas nada.<br \/>\n-L\u00e1stima. \u00bfT\u00fa sabes de qui\u00e9n es sobrino?<br \/>\n-Pues claro, hijo, pues claro&#8230;<br \/>\n-\u00bfY cu\u00e1nto le tienes que tolerar t\u00fa?<br \/>\n-\u00bfEh? No me han dicho nada especial&#8230; supongo que como a todo el mundo.<br \/>\n-Vale, pues ponte en su puesto, que te explico lo que estaba haciendo la criatura y por qu\u00e9 no se lo puedo solucionar.<\/p>\n<p>Le explico, paso a paso y con pruebas c\u00f3mo, un t\u00edo joven, fornido y gafap\u00e1stico perdido (green fashion) es incapaz de meter un puto nombre de usuario y una contrase\u00f1a como $Deity manda, y c\u00f3mo, hacer perder el tiempo de sistemas con semejante incompetencia deber\u00eda ser suficiente para recuperar del c\u00f3digo penal el tema de los latigazos.<\/p>\n<p>-Telita. Esto&#8230; ya se lo explico yo, si eso, Wardog.<br \/>\n-Uuuuuyyy&#8230; me s\u00e9 de uno que tiene miedito del grandull\u00f3n de la verde mirada&#8230;<br \/>\n-Si no es eso, es que&#8230; bueno, que hay que darle una oportunidad.<br \/>\n-S\u00ed, s\u00ed&#8230; vale, expl\u00edcaselo, machote. Suerte.<\/p>\n<p>Clic. Esto no ha terminado aqu\u00ed ni mucho menos. Pues menudo es Atila. No lo presiento, lo s\u00e9.<\/p>\n<p>Pero sin embargo, pasaron m\u00e1s de dos horas. Dos horas para aprender a copiar y pegar en una web. Tiene huevos el tema. Y la santa paciencia que tiene ese supervisor o el miedo que le tiene al gigante verde. Yo sencillamente le he cogido man\u00eda. Es que no puedo con la prepotencia y con la soberbia asquerosa de quien no tiene otra cosa que familia rica. Y que los enchufes no me gustan. Y este lo lleva trif\u00e1sico el pobre. Que podr\u00eda hacer como todo el mundo y dorarle la p\u00edldora, pero es que me toca los cojones que un mentecato de este nivel ocupe el puesto de trabajo que no puede ocupar, por su culpa, alguien competente que est\u00e9 en el paro.<\/p>\n<p>\u00a1Bimbambidubi! \u00a1Dubi!<\/p>\n<p>-Sistemas&#8230; estamos proponiendo la estupidez como deporte ol\u00edmpico.<br \/>\n-\u00bfWardog?<br \/>\n-\u00a1Atila! \u00a1Medalla de oro! \u00a1De platino! \u00a1De adamantium! Oye, \u00bfconseguiste entrar?<br \/>\n-S\u00ed, pero no gracias a t\u00ed, alhaja, que no tieneh paciencia ninguna, joder, que no todoh somoh tan lihtoh como t\u00fa.<br \/>\n-Uy. A t\u00ed te han pegado un repaso en recursos humanos.<br \/>\n-\u00a1Y t\u00fa c\u00f3mo lo sabes!<br \/>\n-Porque ahora sabes con qu\u00e9 est\u00e1s hablando.<br \/>\n-Bueno, que mira, que ya he entrao y sigue sin aparecer la barra esa.<br \/>\n-Veamos&#8230; -conecto con su ordenador y miro una pantalla absolutamente normal.- Oye, que ah\u00ed no falta nada.<br \/>\n-\u00a1C\u00f3mo que no! Ehto&#8230; mira, que aqu\u00ed tiene que salir una barra, que en el del compa\u00f1ero sale y en ehte no.<br \/>\n-Es que no puede salir. Esa barra sale cuando los pedidos no caben en la pantalla, y como caben, no sale la barrita. \u00bfPillas?<br \/>\n-Eso no e as\u00ed.<br \/>\n-Eso es as\u00ed desde que un iframe es un iframe.<br \/>\n-\u00a1Que no me digas cosas raras!<br \/>\n-Asshole!<br \/>\n-\u00a1Joder, Wardog! \u00a1Que te digo yo que eso no eh as\u00edn y punto! \u00a1Que me pongah la barra o se lo digo a mi t\u00edo!<br \/>\n-Uno: \u00a0Eso es as\u00ed por razones que no te voy a enumerar. Dos: No te puedo poner la barra porque esa web no la mantengo yo. Tres: aunque te la pudiera poner, no te iba a servir de nada. Cuatro: \u00a0D\u00edselo a tu t\u00edo. Estoy deseando que me llame.<br \/>\n-T\u00fa ponme la barra y yast\u00e1, hombre, \u00bfqu\u00e9 te cuesta?<br \/>\n-Que sale sola. Que cuando tengas m\u00e1s pedidos la ver\u00e1s. Con eso que tienes no sale porque no hace falta.<br \/>\n-\u00bfY c\u00f3mo s\u00e9 yo que no hay m\u00e1s para abajo?<br \/>\n-Porque no sale la barra.<br \/>\n-\u00bfY si hay m\u00e1s y no los meto?<br \/>\n-Si no hay barra no hay m\u00e1s. Punto.<br \/>\n-Pueh vaya mierda de programa. Ehto no eh as\u00ed en ninguna empresa.- pido por mensajer\u00eda a MKII el curr\u00edculum del pavo este. Lo recibo en cero coma siete segundos y lo abro. Qu\u00e9 eficiencia.<br \/>\n-Veamos&#8230; as\u00ed que has trabajado en empresas en las que esto no era as\u00ed, \u00bfno?<br \/>\n-Po claro, y loh inform\u00e1tico hac\u00edan lo que leh ped\u00edamo.<br \/>\n-A ver&#8230; mmm s\u00ed, aqu\u00ed lo tengo, esa empresa se llamaba&#8230; INEM. Porque t\u00fa no has trabajado en tu puta vida, macho, no terminaste de estudiar y no tienes experiencia profesional de ning\u00fan tipo. \u00a0Con treinta a\u00f1azos ya te vale.<br \/>\n-\u00bfY t\u00fa c\u00f3mo sabes eso?<br \/>\n-Tengo tu curr\u00edculum en pantalla. \u00bfEsto lo imprimes en tarjetas de visita o gastas un folio entero?<br \/>\n-\u00a1Me cagonlaojtiaputaya! \u00a1Vete a tomar por culo!<\/p>\n<p>Y para mi sorpresa, el grandull\u00f3n coge y me cuelga. En vez de enfadarse conmigo, va y me cuelga. En vez de enfrentarse y tirar de la manga a su t\u00edo, me cuelga. Esto ya no es lo que era. Ya no hay emociones ni nada. Enciendo los altavoces de mi ordenador y me pongo a buscar porno. MKII levanta la cabeza cuando escucha los gemidos.<\/p>\n<p>-\u00bfQu\u00e9 co\u00f1o haces?<br \/>\n-Buscando porno.<br \/>\n-Ya, joder, pero, \u00bfahora?<br \/>\n-Es para ayudar a Atila.<br \/>\n-\u00bfCon un v\u00eddeo porno?<br \/>\n-Y si puede ser de zoofilia, mejor.<br \/>\n-Mira, no quiero saberlo.<\/p>\n<p>Luego de buscar un rato, doy con un par de v\u00eddeos as\u00ed escandalosillos. Y por supuesto, el de las dos chicas que se comen un helado de chocolate. Programo unos cuantos comandos remotos que se repetir\u00e1n cada cuatro minutos en el PC de Atila. Programo la hora de inicio para diez minutos m\u00e1s tarde y me voy a por un caf\u00e9. Cerca de pedidos. Cerca de Atila. Busco al supervisor de recepci\u00f3n y le invito a un caf\u00e9.<\/p>\n<p>Comenzamos a charlar cuando al rato sobre el se\u00f1or Atila, se oyen unos gemidos salvajes en toda la oficina. Todo el mundo acude al origen y ve a Atila m\u00e1s colorado que \u00a0un tomate, aporreando in\u00fatilmente el teclado intentando acallar el v\u00eddeo. El supervisor sale escopetado hacia el departamento y se encuentra con un potro de cinco patas haciendo cochinadas con una chinita que grita sentidamente en la pantalla de Atila.<\/p>\n<p>-\u00a1Pero qu\u00e9 est\u00e1s haciendo, Atila!<br \/>\n-Yo&#8230; yo&#8230; \u00a1nada!<br \/>\n-\u00a1Pero como que no! \u00bfEn vez de trabajar te pones a ver porno en la oficina?<br \/>\n-\u00a1Es que Wardog no me arregla nada!<br \/>\n-Como si eso fuera excusa&#8230; Cierra eso ahora mismo y ponte a trabajar, \u00a1vamos!<\/p>\n<p>El chico lo cierra \u00a0como buenamente puede y se pone a trabajar. Al rato, salta otro v\u00eddeo. El supervisor casi escupe el caf\u00e9 al escuchar los gritos brutales que emergen no ya del PC de Atila, sino del despacho. Gritos de asco, de repugnancia, como si estuviesen viendo a 2 chicas comi\u00e9ndose un helado de chocolate fabricado por una de ellas. El supervisor vuelve a rega\u00f1ar a Atila. \u00a0Me da pena el pobre Atila. Mientras veo c\u00f3mo el supervisor le est\u00e1 metiendo el repaso de su vida, me pregunto si no me habr\u00e9 pasado con el pobre chico. Entonces, cuando el supervisor se est\u00e1 girando despu\u00e9s de echarle la bronca y se va a buscar un vaso de agua, sus ojos se cruzan con los m\u00edos. Y ten\u00eda esa mirada. Esos ojos porcinos destilaban la ira t\u00edpica de quien ha sido ultrajado. Pobre. Alza el pu\u00f1o y, sin que el sonido salga de sus labios puedo leer \u00abTe vas a cagar\u00bb. Sonr\u00edo y niego con la cabeza, le se\u00f1alo a \u00e9l y, con el m\u00f3vil acelero la ejecuci\u00f3n del tercer v\u00eddeo: siete maromos gritones de cien kilos cada uno reciben goce sexual de un octavo maromo por turnos. El supervisor se gira y, ya sin miramientos piede a Atila que le acompa\u00f1e.<\/p>\n<p>-\u00a1Pero si ha sido Wardog!<br \/>\n-\u00bfYo?- digo con toda inocencia.<br \/>\n-\u00a1Te he visto!<br \/>\n-\u00a1Ni Wardog ni hostias!- tercia el supervisor- \u00a1Vente, que vamos a hablar con tu t\u00edo, a ver qu\u00e9 es lo que opina \u00e9l!<br \/>\n-Wardog, esta me la pagah por mih muelaj-. Me amenaza secamente. Con la voz fr\u00eda como el hielo.<br \/>\n-OK, ap\u00fantamela.<\/p>\n<p>Y se van por el pasillo, con paso presuroso. Yo me vuelvo a mi puesto y sigo trabajando.<\/p>\n<p>\u00a1Bimbambidubi! \u00a1Dubi!<\/p>\n<p>-Sistemas, uno para todos, todos aomar o&#8217;ulo.<br \/>\n-Hola, Wardog. Soy $Hyperboss.<br \/>\n-\u00a1Hombre, buenos d\u00edas! \u00bfQu\u00e9 se le ofrece?<br \/>\n-Se acaban de ir de mi despacho mi sobrino Atila y su supervisor. Me ha dicho que estaba viendo porno.<br \/>\n-Sep, eso parece.<br \/>\n-Y mi sobrino dice que no le arreglas nada.<br \/>\n-Correcto, pero eso es porque no hay nada que arreglar, simplemente no sabe hacer la o con un canuto.<br \/>\n-\u00bfInsin\u00faas que es un in\u00fatil?<br \/>\n-Exactamente eso.<br \/>\n-T\u00fa tienes los cojones cuadrados, \u00bfverdad? \u00bfNo te estoy diciendo que es mi sobrino?<br \/>\n-Bueno, cuadrados no los tengo, la verdad, pero pelados&#8230; desde hace mucho.<br \/>\n-Ya veo, ya&#8230; y estoy seguro de que lo del porno no ha sido \u00e9l, que t\u00fa has tenido algo que ver.<br \/>\n-Es bonito cuando dos personas, de escalafones distintos en la jerarqu\u00eda se conocen tan bien.<br \/>\n-Pues chico, muchas gracias-. Toma ya. Ahora s\u00ed que me ha pillado. Y yo a la defensiva&#8230;<br \/>\n-De nada, para eso estamos.<br \/>\n-No, en serio, es que me lo endos\u00f3 mi hermana, que le hiciera el favor porque el chico no encuentra trabajo en ning\u00fan sitio. Pero es que es un vago redomado y un ni\u00f1o mimado. Esto que ha pasado me ha venido de perlas para tener una excusa y librarme de \u00e9l.<br \/>\n-No me extra\u00f1a.<br \/>\n-Y el t\u00edo es que no quiere nada m\u00e1s que estar en la oficina, porque ser\u00eda una verg\u00fcenza para \u00e9l trabajar en una obra o de reponedor o cualquier otra cosa.<br \/>\n-Pues no le vendr\u00eda mal una curita de humildad.<br \/>\n-Ya, pero&#8230; ahora que se busque la vida, ya he dado orden de que lo despidan.<br \/>\n-Hombre, no creo yo que sea necesario tanto&#8230;<br \/>\n-\u00bfA qu\u00e9 te refieres?<br \/>\n-A darle un puesto del que depender\u00e1 la buena marcha de los dem\u00e1s.<br \/>\n-\u00bfUn puesto de directivo?<\/p>\n<p>Despu\u00e9s de hablar con $Hyperboss, quedamos en que no le despedir\u00edan. Yo tengo mi corazoncito y no quisiera que se fuera a la calle con la verg\u00fcenza de tener que soportar los comentarios de la gente, que es muy cruel y conseguir que te echen de la empresa de tu t\u00edo tiene miga. No. Que no sea por m\u00ed que se quede sin trabajo.<\/p>\n<p>-\u00bfPero otra vez, Wardog?<br \/>\n-\u00bfQu\u00e9 pasa? \u00a1Lo he perdido!<br \/>\n-T\u00fa no tienes sentimientos.<br \/>\n-Oye, para eso se cre\u00f3 el puesto, \u00bfno?<br \/>\n-No tienes sentimientos, macho. Est\u00e1s hueco.<br \/>\n-Que s\u00ed que tengo, pero es que siempre me los dejo en casa.<\/p>\n<p>\u00a1Bip bup bip!<\/p>\n<p>-\u00bfD\u00edgame?<br \/>\n-Hola Atila, buenos d\u00edas otra vez. \u00bfTenemos correo?<br \/>\n-Pesa\u00edto ereh con el correo, Wardog.<br \/>\n-En absoluto, simplemente me preocupo. \u00bfHas mirado en la bandeja de entrada?<br \/>\n-Mira que se lo digo a&#8230;<br \/>\n-A tu t\u00edo, s\u00ed. Ejem. Vale, y oye, que necesito un l\u00e1piz, que he perdido el m\u00edo.<br \/>\n-Ahora te lo llevo.<br \/>\n-Me corre mucha prisa, por favor.<br \/>\n-\u00a1Te lo llevar\u00e9 cuando pueda!<br \/>\n-Vale, vale, tranquilo, luego te llamo a ver si est\u00e1s m\u00e1s desahogado.<br \/>\n-\u00a1Que no llameh m\u00e1! \u00a1Que ya te lo llevo joder!<br \/>\n-Gracias, hombre, no esperaba menos de un t\u00edo tan entregado a su trabajo.<\/p>\n<p>Clic.<\/p>\n<p>-Wardog, el d\u00eda que se de cuenta de que no pierdes los l\u00e1pices la vais a tener.<br \/>\n-Nah, si este muchacho es un cacho pan.<br \/>\n-Lo que no s\u00e9 es c\u00f3mo siendo el sobrino del $Hyperboss est\u00e1 repartiendo el correo y el material de oficina.<br \/>\n-Misterios de la vida, t\u00fa. Hay que empezar desde abajo, \u00bfno?<\/p>\n<p>Al rato llega Atila por el pasillo, me da mi l\u00e1piz y se va de mala gana, mirando al suelo.<\/p>\n<p>-Atila, \u00bfhas mirado si, por casualidad ten\u00edamos correo?<br \/>\n-\u00a1S\u00ed! \u00a1Y no ten\u00edais nada! \u00a1Ya est\u00e1 bien!<br \/>\n-Vale, si acaso ves que tienes alg\u00fan problema con el correo, me llamas, \u00bfeh?<br \/>\n-\u00a1Pero si no tengo ordenador!<br \/>\n-Uy. Mejor as\u00ed, \u00bfno?<\/p>\n<p>Se gira sin mediar palabra y cierra de un portazo. Mira t\u00fa por d\u00f3nde, hemos creado un puesto de trabajo y un trabajador feliz. Y bueno, Atila que se joda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atila lleva poco tiempo en la oficina. Le han puesto en recepci\u00f3n de pedidos. Es un puesto que siempre ocupan los novatos porque se supone que no tiene m\u00e1s complejidad que elegir el cliente, serie de pedido y meter las cosas que haya solicitado nuestro cliente. Y de hecho, la aplicaci\u00f3n no permite muchas m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-413","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=413"}],"version-history":[{"count":2,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/413\/revisions"}],"predecessor-version":[{"id":987,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/413\/revisions\/987"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}