{"id":401,"date":"2010-05-19T18:25:14","date_gmt":"2010-05-19T17:25:14","guid":{"rendered":"http:\/\/mundowdg.com\/blog\/?p=401"},"modified":"2013-01-27T16:12:30","modified_gmt":"2013-01-27T16:12:30","slug":"el-luser-que-desmembraba-a-los-trabadores","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2010\/05\/19\/el-luser-que-desmembraba-a-los-trabadores\/","title":{"rendered":"El luser que desmembraba a los trabajadores"},"content":{"rendered":"<p>Un $Boss no deja de ser un luser con pintas. Tiene poder, tiene dinero, un coche de la hostia y un chalet en la sierra. E incluso puede que tenga un avi\u00f3n. Ha llegado a donde est\u00e1 de alguna manera, siguiendo su instinto para los negocios ha conseguido ascender y crear una empresa grande. O no.<\/p>\n<p>El caso es que, cuando la cosa crece tanto como en el caso de Suprakillminds, el jefe no puede controlar todo y tiene que delegar. Pero una parte de la neurona del jefe es desconfiada y de vez en cuando a\u00fan quiere enterarse de lo que pasa con su empresa en lugar de estar toc\u00e1ndose los cojones en las Bahamas. Y me parece bien, que conste.<\/p>\n<p>Y cuando la neura se dispara porque resulta que todo el grupo est\u00e1 dando beneficios con la crisis que hay, mirust\u00e9, entonces llamamos a unos se\u00f1ores que cobran un pastizal para que nos digan c\u00f3mo tenemos la empresa. Con dos cojones. Si ser\u00e1 por dinero.<\/p>\n<p>En una primera reuni\u00f3n, se presentan los se\u00f1ores, dan los buenos d\u00edas y, por supuesto, a esa reuni\u00f3n se convocan a los inform\u00e1ticos porque todo el mundo sabe que nos interesan mucho los aspectos financieros y organizativos de la empresa. En dicha reuni\u00f3n inicial se nos pide, porque somos la hostia y podemos hacer de todo con los ojos cerrados, que enviemos un email a todos los gerentes de todas las sedes pidiendo unos datos muy concretos. Y como somos la leche, hacemos caso y enviamos un mail pidiendo que preparen esos datos tan concretos. Nuestros se\u00f1ores con corbata nos piden, adem\u00e1s, que preparemos videoconferencias con todas las sedes para poder hablar cara a cara con los ejecutivos en cuesti\u00f3n. Y como somos la bomba enviamos webcams y micr\u00f3fonos a quien no lo tiene y lo configuramos todo. Y queda de lujo.<\/p>\n<p>A los quince d\u00edas, despu\u00e9s de mucho molar, vuelven los se\u00f1ores que te miran el reloj, te dicen la hora y te cobran un disparate y nos re\u00fanen de nuevo para que vayamos preparando las videoconferencias y que los se\u00f1ores ejecutivos de nuestras sedes puedan aportar los datos que se les solicita y bueno, una peque\u00f1a entrevista sobre la marcha de la sede en cuesti\u00f3n. Preliminares, que dicen que son.<\/p>\n<p>El Skype va que se mata, van pasando directivos de todas las sedes y todos van aportando la informaci\u00f3n que se les ha solicitado. Todo normal y aburrid\u00edsimo. MKII se escapa h\u00e1bilmente y me deja a m\u00ed, como subordinado que soy, a cargo del soporte t\u00e9cnico de la videoconferencia. Conforme sale por la puerta, le mando un mensaje diciendo \u00abPedazo de hijo de puta est\u00e1s hecho. Hoy la comida la pagas t\u00fa. Y me pienso meter entre pecho y espalda un chulet\u00f3n como el mapa de Australia\u00bb. Me responde, el muy cabr\u00f3n que \u00abPoco se me hace. Que disfrutes.\u00bb<\/p>\n<p>El BOFH-Zen ha iluminado tambi\u00e9n a MKII y oye, se ha vuelto un tipo simp\u00e1tico. Sigue siendo un poco estirado, pero se puede trabajar con \u00e9l. La ma\u00f1ana transcurre lenta y pringosamente. Las corbatas van hablando y mi camiserta y yo nos dedicamos a establecer las conexiones (que ya ves t\u00fa) y a twitear compulsivamente mientras tanto. Hasta que la corbata jefe me pide algo:<\/p>\n<p>-Wardog, por favor, con\u00e9ctanos con Misif\u00fa, de Killminds.<br \/>\n-\u00bfEst\u00e1 usted seguro?<br \/>\n-Claro, \u00bfpor qu\u00e9 no iba a estarlo?<br \/>\n-Claro, qu\u00e9 tonter\u00eda.<\/p>\n<p>Busco en la lista a Misif\u00fa y le doy a videollamada. Espero. Espero. Espero&#8230; nada.<\/p>\n<p>-\u00bfHay alg\u00fan problema?<br \/>\n-S\u00ed, que no responde a la llamada. Lo intento de nuevo.<\/p>\n<p>Espero, espero, espero&#8230; qu\u00e9 raro. Le vuelvo a dar. En ese momento suena en mi m\u00f3vil \u00abThe best is yet to come\u00bb.<object style=\"width: 425px; height: 350px;\" width=\"425\" height=\"350\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"scale\" value=\"exactfit\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/L6XRuOPJNko&amp;feature\" \/><embed style=\"width: 425px; height: 350px;\" width=\"425\" height=\"350\" type=\"application\/x-shockwave-flash\" src=\"http:\/\/www.youtube.com\/v\/L6XRuOPJNko&amp;feature\" scale=\"exactfit\" \/><\/object><\/p>\n<p>-Misif\u00fa, te tengo dicho que \u00e9ste tel\u00e9fono es s\u00f3lo por si se acaba el mundo.<br \/>\n-Perdona, Wardog, es que tengo un mensaje en pantalla que dice \u00abSupraKillminds Llamando\u00bb y no s\u00e9 qu\u00e9 tengo que hacer.<br \/>\n-\u00bfT\u00fa lees lo \u00a0que te sale en la pantalla o te quedas con la boca abierta y la mano en el rat\u00f3n?<br \/>\n-No hombre, yo lo leo, pero es que no le he dado a nada por si rompo algo.<br \/>\n-T\u00edo, que s\u00f3lo tienes que darle al bot\u00f3n verde.<br \/>\n-Ah vale, vale.<br \/>\n-Te cuelgo y te llamo por Skype. C\u00f3gelo.<\/p>\n<p>Clic. Relanzo la llamada. Ahora s\u00ed que contesta. Me relajo en la silla y me dispongo a dormitar otro rato mientras las corbatas entrevistan al figura este. Pero algo me saca de mi mundo particular. La corbata jefe me requiere:<\/p>\n<p>-Wardog, hay un problema con el v\u00eddeo.<br \/>\n-Vaya por $deity&#8230; Misif\u00fa, \u00bfme oyes?<br \/>\n-Perfectamente.<br \/>\n-\u00bfD\u00f3nde cojones tienes la webcam?<br \/>\n-Uy. En el suelo. Espera.- La imagen se empieza a mover. Vemos las pelusas de detr\u00e1s de la mesa. Se oyen golpes y se ve la mano de Misif\u00fa varias veces maniobrando para colocar la c\u00e1mara en su sitio.- Ya est\u00e1.<br \/>\n-Cojonudo, Misif\u00fa. Tenemos una panor\u00e1mica espectacular de tu ingle.<br \/>\n-\u00bfNo se me ve?<br \/>\n-Los huevos s\u00ed. Pon la c\u00e1mara encima del monitor, criatura.<\/p>\n<p>Los se\u00f1ores encorbatados est\u00e1n ojipl\u00e1ticos perdidos. Temo que a uno de ellos, con bastante cara de rana se le salte uno de la cara y salga rodando. M\u00e1s que nada porque seguro que me toca a m\u00ed enchuf\u00e1rselo de nuevo.<\/p>\n<p>-Ya est\u00e1 encima del monitor.<\/p>\n<p>Las corbatas contraen la cara en un rictus forzado para mantener la seriedad. A m\u00ed esto me parece tan absolutamente normal&#8230;<\/p>\n<p>-Misif\u00fa, tu pared no nos interesa. Por alguna extra\u00f1a raz\u00f3n, esta gente te quiere ver la cara. Dale la vuelta a la c\u00e1mara.<br \/>\n-\u00a1Uf! Voy.<\/p>\n<p>La imagen gira 180\u00ba hasta que la pared se sigue viendo, pero del rev\u00e9s y se escapan dos carcajadas. Yo respiro hondo, apoyo la cabeza en una mano, con el codo apoyado en la mesa de juntas y con mi tono m\u00e1s seco le digo:<\/p>\n<p>-As\u00ed no, animal, g\u00edrala hacia t\u00ed.<br \/>\n-\u00a1Aaaah! \u00a1Si ya dec\u00eda yo que&#8230; espera!<\/p>\n<p>Le da la vuelta a la c\u00e1mara. Las corbatas empiezan a toser cuando le ven a \u00e9l al final de los brazos. Y del rev\u00e9s. Le ha dado la vuelta en el eje X y se le ve a \u00e9l del rev\u00e9s. Virgen santa. Guardo silencio simplemente por ver qu\u00e9 pasa. El hombre coloca cuidadosamente la c\u00e1mara sobre el monitor del rev\u00e9s. Cuando parece satisfecho la suelta. La c\u00e1mara gira r\u00e1pidamente impulsada por el cable retorcido y se la pega contra el suelo despu\u00e9s de llevarse por el camino el lapicero y provocando un estr\u00e9pito considerable. Las corbatas m\u00e1s j\u00f3venes se frotan los ojos llorosos por la risa. Me incorporo e intento relajarme. Empat\u00eda. Hay que usar la empat\u00eda. Lo suyo ser\u00eda meterse dentro de su mente y pensar como \u00e9l. Bah. No funcionar\u00eda. Si alg\u00fan d\u00eda me veo en esa situaci\u00f3n me suicido con un batido de t\u00f3ner magenta.<\/p>\n<p>-Misif\u00fa, el agujero de la c\u00e1mara, mirando hacia t\u00ed. Y la cosa plana de la c\u00e1mara es el pie, eso debe ir hacia abajo. Y el cable debe salir por la parte de atr\u00e1s, sin retorcerse.<br \/>\n-Voy, voy&#8230;- coloca todo correctamente y se sit\u00faa delante de la c\u00e1mara.- \u00bfYa? \u00bfYa est\u00e1 bien?<br \/>\n-S\u00ed, solamente ret\u00edrate un poco de la c\u00e1mara, que no vemos m\u00e1s que nariz.<br \/>\n-Ah, vale&#8230;- se retira y se le ve ya medio cuerpo. Su mirada est\u00e1 fija en el objetivo de la c\u00e1mara y suda profusamente.- \u00a1Anda! \u00a1Si me veo en la pantalla del ordenador!<\/p>\n<p>Demoledor. Las corbatas se recomponen, se atusan un poco y comienzan el cuestionario. Ya funciona todo bien, simplemente tengo que esperar a que terminen y mientras, miro el correo. Comienzan las presentaciones, la explicaciones de por qu\u00e9 hacen lo que hacen. Mal que me pese, mi yo voluntarioso sigue atento a la conversaci\u00f3n. Fueron muchos a\u00f1os con Misif\u00fa, y le conozco como si le hubiese parido.<\/p>\n<p>-Y bien, se\u00f1or Misif\u00fa, me imagino que tendr\u00e1 preparados los datos que le solicitamos por email.<br \/>\n-S\u00ed, claro, aqu\u00ed lo tengo todo bien especificado.<br \/>\n-Bien, comencemos. En la divisi\u00f3n uno, que corresponde a ventas B2B, \u00bfqu\u00e9 cantidad aporta?<br \/>\n-Chopocientos millones taitantosmil euros con cincuenta.<br \/>\n-Perfecto. Qu\u00e9 exactitud. \u00bfCu\u00e1l es el importe de la divisi\u00f3n 2, la B2C?<br \/>\n-Chorrocientos millones atraspacientosmil euros con treinta y dos.<br \/>\n-Muy bien. D\u00edgame el importe total de B2B+B2C+ otros ingresos.<br \/>\n-Cero.<\/p>\n<p>Un quintal de plomo cae en la sala de juntas. Salgo de mi letargo y veo c\u00f3mo todos los encorbatados entes miran fijamente la pantalla sin mover un m\u00fasculo. Les ha pillado de sopet\u00f3n. Misif\u00fa est\u00e1 atus\u00e1ndose el pelo mientras espera la siguiente pregunta. Sostiene un papel manoseado en sus temblorosas manos. Salir en la tele le pone nervioso.<\/p>\n<p>La corbata jefe comete el error de repetir la pregunta.<\/p>\n<p>-S\u00ed, s\u00ed, cero.-Responde Misif\u00fa.<br \/>\n-\u00bfPero c\u00f3mo va a ser cero si entre B2B y B2C ya son quincuitantos millones?<br \/>\n-Hombre, visto as\u00ed&#8230;<br \/>\n-Misif\u00fa. Abre la puta hoja de c\u00e1lculo y ampl\u00eda el ancho de la columna de los importes- digo yo desde la sombra donde me he refugiado, ya de pie y apoyado c\u00f3modamente contra la pared para tener una mejor perspectiva de la reuni\u00f3n. Las corbatas se giran para mirarme extra\u00f1ados. Misif\u00fa manipula en el ordenador y al cabo de un rato asiente con la cabeza.<br \/>\n-Pues claro, ten\u00eda usted raz\u00f3n son dosquincuitantos millones septenciosmil chopocientos con dos&#8230; es que sal\u00edan unos s\u00edmbolos en el papel y claro, yo pensaba que eso era cero.<\/p>\n<p>El quintal pisa m\u00e1s fuerte a\u00fan. Las corbatas cuchichean entre s\u00ed. Misif\u00fa sigue fijo en pantalla, enrollando y desenrollando su papel.<\/p>\n<p>-En fin. D\u00edgame, \u00bfhan invertido en I+D durante el a\u00f1o pasado?<br \/>\n-No.<br \/>\n-\u00bfEn maquinaria?<br \/>\n-No.<br \/>\n-\u00bfEn mejora de procesos productivos?<br \/>\n-No.<br \/>\n-\u00bfAlguna inversi\u00f3n en otras \u00e1reas de mejora?<br \/>\n-No, no.<br \/>\n-Bien, el total entonces es cero, \u00bfno?<br \/>\n-Mmmm&#8230; no, me salen tresgofientosmil euros.<br \/>\n-\u00bfEn inversiones de mejoras?<br \/>\n-S\u00ed.<br \/>\n-\u00bfPero c\u00f3mo puede salir esa cantidad si dice que no han invertido en mejoras?<br \/>\n-Ah&#8230; pues no lo s\u00e9. Tendr\u00e9 que consultar a mi equipo, la suma no debe estar bien.<br \/>\n-Misif\u00fa, te has saltado una l\u00ednea. Es la de arriba.-El equipo de seda me mira de nuevo. Sus rostros reflejan extra\u00f1eza. Mi voz es tranquila y segura. Tanto que ni siquiera estoy frente a la pantalla donde aparece Misif\u00fa. Puedo operar con estos lusers con los ojos cerrados.<br \/>\n-\u00a1Uy! \u00a1Es verdad! \u00a1Claro! Con tanto cero es normal que uno se l\u00ede&#8230;<br \/>\n-Claro, claro&#8230; la respuesta \u00a0era de l\u00f3gica, pero bueno.- De l\u00f3gica dice el payo. Esos no han visto la l\u00f3gica ni a cien metros en su puta vida.- Bien&#8230; pasemos a beneficios por familia de producto. Vaya dici\u00e9ndome la familia y el porcentaje de beneficio final, por favor.<br \/>\n-En todas tenemos un 100% de beneficio.<\/p>\n<p>\u00a1\u00a1BLOM!! Sobre el quintal de antes, cae otro. Media sonrisa se me dibuja en la cara. No digo nada, y a\u00fan as\u00ed, todos me miran en busca de una respuesta al interrogante. Me hago el loco. Que se luzca.<\/p>\n<p>-\u00bfC\u00f3mo&#8230;? \u00bfC\u00f3mo van a tener un 100% de beneficio? \u00bfBeneficio total?<br \/>\n-Un 100%, s\u00ed se\u00f1or- contesta Misif\u00fa orgulloso de su gesti\u00f3n.- Un 100% en todo.<br \/>\n-Pero&#8230; pero vamos a ver. No puede ser, habr\u00e1 que descontar materia prima, costes fijos, mano de obra&#8230; no s\u00e9&#8230; \u00a1ALGO!<br \/>\n-Pues mi sistema me dice que tenemos un 100% de beneficio por art\u00edculo.<br \/>\n-Misif\u00fa, abre el programa de gesti\u00f3n y dime el coste del farulentador cinlindroc\u00fabico azul.- Todo el mundo me mira. Hago como que no me doy cuenta. Esto es muy divertido.<br \/>\n-Cero.<br \/>\n-Vale. M\u00edrame el precio de coste del bimolador de arrimarseto.<br \/>\n-Mmmm&#8230; cero.<br \/>\n-Vale. Todos los costes est\u00e1n a cero y t\u00fa sabes por qu\u00e9, \u00bfverdad?<br \/>\n-Mmmm.. ya veo, ya&#8230; es que ten\u00edamos algunos costes mal, y para no liarnos le ped\u00ed a Fluffy que los pusiera todos a cero para empezar en limpio.<br \/>\n-O sea, para meter los costes a m\u00e1s de cuatrocientasmil referencias, escandallos y tiempos. Con dos cojones. \u00bfY por qu\u00e9 no hay nada metido, Misif\u00fa querido?<br \/>\n-Pues&#8230; porque Fluffy me dijo que \u00e9l no lo iba a hacer porque no es su tarea, y yo le dije \u00ab\u00a1pues los tienes que poner porque eres un miembro m\u00e1s de la plantilla!\u00bb y el se segu\u00eda negando y ah\u00ed estamos todav\u00eda.<br \/>\n-Fluffy est\u00e1 para soporte inform\u00e1tico, no para hacer lo que no quiere hacer nadie. Vamos, que nadie se ha querido hacer cargo de los costes y as\u00ed llev\u00e1is ni se sabe el tiempo.<br \/>\n-Unos meses, s\u00ed.<br \/>\n-Unos meses sin saber si ten\u00e9is beneficios con las ventas o no. Bien. Cojonudo.<\/p>\n<p>Los encorbatados se\u00f1ores asisten a la conversaci\u00f3n estupefactos y escribiendo autom\u00e1ticamente con sus bol\u00edgrafos. Estos pavos fijo que tienen un blog y est\u00e1n tomando nota de todo.<\/p>\n<p>-Se\u00f1or&#8230; se\u00f1or Misif\u00fa- dice la corbata portavoz- dejemos la cuesti\u00f3n econ\u00f3mica para una visita personalizada.- Sus hab\u00e9is cagado. Vais a tener a esta gente escarbando en vuestra mierda y lo vais a disfrutar de lo lindo. Los m\u00e1s jovenes de los oscuros trajes sonr\u00eden y comentan entre ellos. Alguna risita se les escapa. Misif\u00fa se da cuenta y se pone a\u00fan m\u00e1s nervioso.- Bien, pasemos a personal. D\u00edgame, por favor, el total de personas que trabajan en la empresa.<br \/>\n-Sispucientas ocho con setenta y tres.<\/p>\n<p>\u00a1PLOM! Una nube pesada como una ballena azul pre\u00f1ada de mellizos cae sobre la mesa y se hace un silencio denso, tanto que s\u00f3lo se oye el zumbido del ordenador. Nadie se mueve. Ni respiran. El ambiente\u00a0\u00a0est\u00e1 tenso como la cuerda de un arco.<\/p>\n<p>-Misif\u00fa.<br \/>\n-Dime, Wardog.<br \/>\n-\u00bfA qui\u00e9n le has cortado un trozo?<br \/>\n-\u00bfC\u00f3mo dices?<br \/>\n-\u00bfC\u00f3mo vas a tener trabajando a sispucientas ocho personas con setenta y tres? \u00bfT\u00fa sabes que aunque haya un lisiado que le falte una pierna o alg\u00fan otro miembro cuenta como persona entera?<br \/>\n-Pues&#8230; pues&#8230;- se \u00a0revuelve nervioso en la silla mientras las carcajadas arrecian en la sala, ya sin pudor.- No s\u00e9, yo&#8230; claro, qu\u00e9 falta de respeto, no contar a alguien entero&#8230;<\/p>\n<p>Bosscorbata intenta poner orden y que dejen de re\u00edr. No puede contenerse ni \u00e9l mismo. Yo tambi\u00e9n ando descojonado por la sala.<\/p>\n<p>-\u00a1Jajaja! \u00a1Jaaaaa! Perd\u00f3n se\u00f1or Misif\u00fa&#8230; es que&#8230; me ha hecho gracia el chiste de Wardog&#8230; d\u00edgame por favor, el n\u00famero de mujeres que trabaja en la empresa&#8230;<\/p>\n<p>Todo el mundo se queda expectante con la carcajada preparada en la boca, saben que va a pasar algo. Acechan ansiosos y todo. Misif\u00fa mira detenidamente el papel. El sudor le corre por la cara a mares y est\u00e1 rojo como un tomate. Las gafas, levemente empa\u00f1adas. Revisa el dato una y otra vez, en el papel y en el ordenador. Al fin se da por satisfecho y contesta:<\/p>\n<p>-Trescientas doce con cincuenta.<\/p>\n<p>Este t\u00edo no defrauda.<\/p>\n<p>-\u00a1Muy bien, Misif\u00fa! \u00a0\u00bfY qu\u00e9 tenemos como media mujer? \u00bfUn marimacho o una princesita f\u00e1lica?<\/p>\n<p>Las carcajadas arrecian de nuevo en la sala hasta el punto de que se tumban todos en la mesa y dan pu\u00f1etazos. Yo sonr\u00edo y disfruto. Misif\u00fa a\u00fan aguanta estoicamente frente a la c\u00e1mara, intentando sujetar el papel como puede, porque est\u00e1 h\u00famedo y se le resbala. Se va a deshidratar. Cada vez que toca el papel deja la marca h\u00fameda de sus dedos impresa. Gran Corbata se incorpora de golpe y me dice muy serio:<\/p>\n<p>-Oye, Wardog, \u00bfno ser\u00e1 que est\u00e1 dici\u00e9ndonos porcentajes?<br \/>\n-No creo que haya un trecientos doce por ciento de mujeres.- Este tambi\u00e9n se las gasta finas finas&#8230;<br \/>\n-No, claro&#8230; Se\u00f1or Misif\u00fa, por favor, \u00bfqu\u00e9 porcentaje del personal usa ordenador?<br \/>\n-El 100%- responde con contundencia.<br \/>\n-\u00bfTodo el mundo usa ordenador?<br \/>\n-S\u00ed, es sorprendente, pero todo el mundo lo usa.<br \/>\n-\u00bfTodos, todos? \u00bfY qu\u00e9 hacen con el ordenador?<br \/>\n-Ah, no s\u00e9.<br \/>\n-Hombre, si todos usan, habr\u00e1 que saber m\u00e1s o menos qu\u00e9 hacen con \u00e9l.<br \/>\n-No lo s\u00e9. Simplemente hemos ido preguntando si usan ordenador y todos han dicho que s\u00ed, pero ya qu\u00e9 hacen con \u00e9l en su casa no se lo hemos querido preguntar.<\/p>\n<p>Y ooootra tormenta de carcajadas. Misif\u00fa no entiende esta vez por qu\u00e9 se r\u00eden.<\/p>\n<p>-Bien, esa pregunta la dejaremos pendiente para la visita que les haremos. Ahora&#8230;- se para en medio de la pregunta y rectifica aguantando la risa como buenamente puede.- Me imagino que todos usan internet, \u00bfverdad?<br \/>\n-Mmmm&#8230; no, claro. Algunos \u00a0dicen que a\u00fan no les han puesto la l\u00ednea, pero que tienen pensado ponerla.<\/p>\n<p>Esto ya es una fiesta. \u00a1Ole! \u00a1Alegr\u00eda! \u00a1Venga risas! Los cuervos elegantes se repatingan en las sillas y se agarran el est\u00f3mago. Algunos incluso est\u00e1n ya sin fuerzas y jadean la risa como buenamente pueden.<\/p>\n<p>La Gran Corbata se recompone y cierra la carpeta correspondiente a Killminds. Se ajusta el lazo, pone la espalda recta, los brazos sobre la mesa y mira a la c\u00e1mara como un presentador de telediario. Es incre\u00edble lo serio que se puede poner un t\u00edo que lagrimea como el manantial de Lourdes.<\/p>\n<p>-Bien, se\u00f1or Misif\u00fa, dentro de unos d\u00edas le avisaremos para concertar una cita e inspeccionar los datos de la empresa. Muchas gracias por su inestimable colaboraci\u00f3n.<br \/>\n-Entonces&#8230;\u00bfno hemos aprobado?- dice triste y compungido.<br \/>\n-\u00a1Jaaaajaja&#8230; perd\u00f3n! Esto no era un examen, hombre, era simplemente recopilar datos, pero vamos a visitarles para verificar nosotros mismos la obtenci\u00f3n de los mismos.<br \/>\n-Bueno&#8230; pues cuando ustedes quiera, esta es su casa y aqu\u00ed estamos para lo que necesiten.<br \/>\n-Perfecto, muchas gracias. Hasta pronto.<\/p>\n<p>Me dirijo hacia el ordenador para terminar la llamada. De pronto se oye por los altavoces la voz de Misif\u00fa.<\/p>\n<p>-Me cago hasta en la puta madre que los ha parido a todos los listillos esos, panda de subnormales&#8230; datos, datos, datos&#8230; \u00a1Y yo qu\u00e9 cojones s\u00e9! \u00a1Por culo les van a dar! \u00a1A ver si se creen que saben m\u00e1s que yo! \u00a1Si no fuera por m\u00ed esto se hab\u00eda ido a la mierda hace a\u00f1os! \u00a1Ahora van a venir unos gilipollas a arreglar el mundo, no te jode!<br \/>\n-\u00bfMisif\u00fa?<br \/>\n-\u00bfWardog?- Misif\u00fa aparece en la pantalla con una cara de susto de libro, tal como si hubiese visto al coco vestido de faralaes.- \u00bfEsto no cuelga solo?<br \/>\n-No. No cuelga solo.<br \/>\n-\u00a1C\u00f3mo se cuelga! \u00a1C\u00f3mo se cuelga!- Dice rojo como un tomate, muy cerca de la c\u00e1mara mientras golpea el teclado nervioso como una colegiala a los mandos de un avi\u00f3n de combate.<br \/>\n-Deja, ya cuelgo yo, machote. Que pases un buen d\u00eda.<br \/>\n-Ay madre m\u00eda&#8230;<\/p>\n<p>Cuelgo y conecto al siguiente. Mira que \u00a0este hombre y los ordenadores se llevan mal. Pero qu\u00e9 bestia es. Qu\u00e9 bestia. Es un Vega Sicilia de los lusers. Mejora con el tiempo. \u00bfA que es adorable?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un $Boss no deja de ser un luser con pintas. Tiene poder, tiene dinero, un coche de la hostia y un chalet en la sierra. E incluso puede que tenga un avi\u00f3n. Ha llegado a donde est\u00e1 de alguna manera, siguiendo su instinto para los negocios ha conseguido ascender y crear una empresa grande. O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-401","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=401"}],"version-history":[{"count":2,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/401\/revisions"}],"predecessor-version":[{"id":985,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/401\/revisions\/985"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}