{"id":361,"date":"2010-01-12T15:17:55","date_gmt":"2010-01-12T12:17:55","guid":{"rendered":"http:\/\/wardog.nnecom.com\/blog\/?p=361"},"modified":"2010-01-12T15:17:55","modified_gmt":"2010-01-12T12:17:55","slug":"si-he-cambiado-el-aspecto-del-blog","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2010\/01\/12\/si-he-cambiado-el-aspecto-del-blog\/","title":{"rendered":"S\u00ed, he cambiado el aspecto del blog"},"content":{"rendered":"<p>Pues s\u00ed. Que como he vuelto a cambiar el blog de sitio, ahora sin l\u00edmites de transferencia, con un rendimiento superior, y la hostia en verso (una m\u00e1quina virtual enterita para alojar el blog), pues ya he aprovechado y le he lavado la cara a esto.<\/p>\n<p>\u00bfPor qu\u00e9? Pues porque me ha dado la gana. Que para eso el blog es m\u00edo.<\/p>\n<p>Ya pod\u00e9is decir que es feo (tu opini\u00f3n es subjetiva y no la comparto), que en IE no se ve bien (usad otra cosa, co\u00f1o), que en el m\u00f3vil no se lee bien (mentira cochina, que yo lo veo estupendamente tanto en WM5,6 y Symbian).<\/p>\n<p>Como ver\u00e9is hay algunas zarandajas m\u00e1s, como el twitter y las etiquetas (a\u00fan tengo que etiquetar el 80% del blog, miat\u00fa). Pero bueno, que si antes era feo (que lo era), y lo le\u00edais, espero seguir contando con vosotros un par de siglos m\u00e1s.<\/p>\n<p>Porque yo no tengo planeado morirme hasta los 327 a\u00f1os. Ea. Que lo disfrut\u00e9is.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues s\u00ed. Que como he vuelto a cambiar el blog de sitio, ahora sin l\u00edmites de transferencia, con un rendimiento superior, y la hostia en verso (una m\u00e1quina virtual enterita para alojar el blog), pues ya he aprovechado y le he lavado la cara a esto. \u00bfPor qu\u00e9? Pues porque me ha dado la gana. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[9],"class_list":["post-361","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-blog"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}