{"id":315,"date":"2005-09-19T10:55:00","date_gmt":"2005-09-19T10:55:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=6"},"modified":"2005-09-19T10:55:00","modified_gmt":"2005-09-19T10:55:00","slug":"momentos-estelares","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2005\/09\/19\/momentos-estelares\/","title":{"rendered":"Momentos estelares."},"content":{"rendered":"<p><a href=\"http:\/\/photos1.blogger.com\/blogger\/2777\/1359\/1600\/JOOOODEEEEER.jpg\"><img decoding=\"async\" style=\"display:block;text-align:center;cursor:pointer;margin:0 auto 10px;\" src=\"http:\/\/photos1.blogger.com\/blogger\/2777\/1359\/320\/JOOOODEEEEER.jpg\" alt=\"\" border=\"0\" \/><\/a><\/p>\n<p>Y as\u00ed empez\u00f3 una ma\u00f1ana&#8230; Es un mensaje que le enviaron a mi compa\u00f1era Rubita desde una de las tiendas. He tapado las direcciones y el nombre de la empresa, pero esa captura es ver\u00eddica, de hace unos meses.<br \/>Hasta los cojones&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y as\u00ed empez\u00f3 una ma\u00f1ana&#8230; Es un mensaje que le enviaron a mi compa\u00f1era Rubita desde una de las tiendas. He tapado las direcciones y el nombre de la empresa, pero esa captura es ver\u00eddica, de hace unos meses.Hasta los cojones&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-315","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=315"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/315\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}