{"id":188,"date":"2008-07-10T16:15:37","date_gmt":"2008-07-10T15:15:37","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=188"},"modified":"2008-07-10T16:15:37","modified_gmt":"2008-07-10T15:15:37","slug":"hola-otra-vez","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2008\/07\/10\/hola-otra-vez\/","title":{"rendered":"Hola otra vez"},"content":{"rendered":"<p>Eso que dicen de que el d\u00eda que te casas es un d\u00eda muy especial, es verdad. Y mira que yo no era partidario del matrimonio. Pero la verdad es que disfrutamos como enanos.<\/p>\n<p>Ya desde por la ma\u00f1ana fueron llegando familiares y amigos al hotel y fuimos junt\u00e1ndonos en torno a una cerveza y pudimos charlar tranquilamente. La verdad es que yo no estaba nervioso ni nada, mirust\u00e9. Comimos a tragullones porque llegaron los fot\u00f3grafos esos que te persiguen a todas partes y hab\u00eda que empezar a hacer el parip\u00e9. La suerte es que eran muy majos y muy profesionales, aunque yo hubiese preferido las fotos de los colegas y de la familia nada m\u00e1s, pero la verdad es que el trabajo que hacen estos profesionales es cojonudo.<\/p>\n<p>Luego vino el momento de montarse en el coche camuflado e ir a la iglesia a esperar a la Chuchi. La gente fue llegando a la iglesia e iba salud\u00e1ndolos como es preceptivo. A la hora convenida mas 15 minutitos, ya suena la marcha nupcial y entra la Chuchi enganchada por el brazo a su padre. Qu\u00e9 cosa m\u00e1s bonita, oye, lo guapa que iba mi se\u00f1ora esposa. Esposa. Anda que no suena raro&#8230;<\/p>\n<p>La ceremonia fue la leche. El cura un cachondo del quince, con momento Pepe Viyuela inclu\u00eddo, tir\u00f3 el librito, el ramo, el micr\u00f3fono&#8230; Al salir, como no esperaba menos, diecisiete toneladas de arroz y catorce de confeti. Nos cost\u00f3 bastante desenterrarnos, la verdad. Y eso que mi hermano abri\u00f3 un bote de confeti del rev\u00e9s y le estall\u00f3 en la tripa&#8230;<\/p>\n<p>Y ya el banquete fue el despiporre. No \u00e9ramos muchos, la verdad, no quer\u00edamos tener en el banquete a gente que no conoci\u00e9semos. Risas, c\u00e1nticos, bailes&#8230; La verdad es que las dos mesas centrales en las que estaban los amigos de siempre y algunos nuevos armaron un esc\u00e1ndalo \u00e9pico. La fiesta se extendi\u00f3 a los balcones que daban a los jardines del hotel donde lo celebramos.<\/p>\n<p>Cortada la tarta, a bailar, oiga. Nosotros abrimos el baile y ya no par\u00f3 en toda la noche. Barra libre que tuvimos que ampliar porque la gente estaba disfrutando como vacas. Creo que bail\u00e9 hasta con el camarero y eso que era clavaito a Bernardo Mar\u00edn.<\/p>\n<p>Una vez borrachos, cansados y af\u00f3nicos (los amigos es que lo dan todo en la bodas, la madre que los pari\u00f3), fuimos a armarla un poco por el hotel. Una amenaza velada del guardia de seguridad de llamar a la polic\u00eda si nos acerc\u00e1bamos un poco m\u00e1s a la piscina nos hizo retroceder y armarla un poco por el hotel. No vali\u00f3 que uno de los que me llevaba a hombros dijese que no llamase, que ya estaba \u00e9l, que es guardia civil.<\/p>\n<p>Dos energ\u00famenos que nos acompa\u00f1aban recolectaron todas las macetas de los pasillos de dos plantas y las mandaron de paseo en los ascensores, vaciaron los cestos de caramelos de recepci\u00f3n&#8230; Lo t\u00edpico, vamos.<\/p>\n<p>Al d\u00eda siguiente, a comer con los amiguetes y vuelta a casa a morirnos un poco, que est\u00e1bamos reventados totalmente.<\/p>\n<p>A los dos d\u00edas, al aeropuerto y a Bali. Si alguien est\u00e1 pensando en ir a esa isla, que no se lo piense, que vaya de cabeza y que hable antes conmigo que le recomiendo un gu\u00eda bastante bueno. Una luna de miel genial. Paisajes de pel\u00edcula, gastronom\u00eda excelente, una atenci\u00f3n por parte de todo el mundo excepcional; una cultura rica llena de influencias de mil sitios; arte, espect\u00e1culo y calma. Mucha calma, que falta nos hac\u00eda a los dos.<\/p>\n<p>Un detalle: conducen de puta madre. Hay chopocientasmil motos, cohes y camiones por las carreteras. Las carreteras son super estrechas excepto en las ciudades grandes Y NO HAY ATASCOS. Si me lee alguien de la DGT, por favor, que se traigan a 50 balineses, les ense\u00f1en a conducir por la derecha (all\u00ed circulan por la zurda) y que los suelten en los puntos de entrada a Madrid. En cinco minutos disuelven los atascos que ni el Kalia ese. La madre que los pari\u00f3. Una carretera de cinco metros de ancho se convierte en v\u00eda r\u00e1pida, autopista de cuatro carriles y circuito de velocidad cada veinte segundos. Te digo yo que a estos los sueltas aqu\u00ed y aprovechan hasta el guardara\u00edl.<\/p>\n<p>En fin, una boda para mi gusto perfecta. Todo el mundo se fue contento y se divirti\u00f3 de lo lindo. A\u00fan hoy me consta que se sigue hablando de la boda, fue una fiesta consecuente con el motivo.<\/p>\n<p>\u00bfKillminds? Para la siguiente entrega. \u00a1Gracias por esperar!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eso que dicen de que el d\u00eda que te casas es un d\u00eda muy especial, es verdad. Y mira que yo no era partidario del matrimonio. Pero la verdad es que disfrutamos como enanos. Ya desde por la ma\u00f1ana fueron llegando familiares y amigos al hotel y fuimos junt\u00e1ndonos en torno a una cerveza y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-188","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/188\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}