{"id":17,"date":"2005-11-04T17:45:00","date_gmt":"2005-11-04T17:45:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=17"},"modified":"2005-11-04T17:45:00","modified_gmt":"2005-11-04T17:45:00","slug":"reflexiones-de-cerebro-abotargado","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2005\/11\/04\/reflexiones-de-cerebro-abotargado\/","title":{"rendered":"Reflexiones de cerebro abotargado"},"content":{"rendered":"<p>Que discutiendo de otras cosas con mi jefe estaba pensando en la religion cat\u00f3lica, todo esto a cuenta de que mi jefe dice que en esta empresa es Dios.<br \/>Y uno, pues se da cuenta de que los cat\u00f3licos se lo tienen montao de miedo. Manejan al personal que ya le gustar\u00eda a mi jefe hacerlo ni parecido. A ver, que veamos:<br \/>-El coste de fabricaci\u00f3n del producto es cero patatero. Cero pa-ta-te-ro. No hacen falta materias primas, como mucho imprimir un par de libretos para los juglares esos que se plantan en los altares de las iglesias a dirigir la obra.<br \/>-Infraestructuras gratis casi siempre. No vamos a gastar millonadas en iglesias y catedrales. Eso que lo construya alg\u00fan pr\u00edncipe o alg\u00fan conde o alg\u00fan otro gili que se haya cre\u00eddo el cuento este que vendemos. Y que las hagan bien y que duren, que no estamos pa derrochar. Y si se estropea que lo arregle el gobierno, oiga, que semos pobres, payo.<br \/>Y ahora viene lo cojonudo de verdad, los trabajadores:<br \/>A estos les meten el cuento (recordemos, el producto) tan a fondo o m\u00e1s que a los clientes (los que van a misa a hacer aerobic light y a cantar salves al se\u00f1or) y hacen jurar tres votos: pobreza, castidad y obediencia.<br \/>Pobreza: Para que esta gente no pida aumentos de sueldo, que los peces gordos no podr\u00e1n tener lujo ninguno de otra manera, v\u00e1lgame Dios.<br \/>Castidad: Si no tienen familia, menos gastos van a tener, menos bocas que alimentar para la santa iglesia catolica, apostolica, romana y rebozada.<br \/>Obediencia: Eliminamos la jubilaci\u00f3n, las pagas extras, las vacaciones, huelgas de curas&#8230; y como te portes mal, te castiga Dios, que aunque en el libreto que te hemos dado no lo ponga, el lo piensa, lo que pasa es que a los ap\u00f3stoles se les olvid\u00f3 adjuntar esos folios.<br \/>Y ah\u00ed tenemos la empresa redonda. No produce nada, no tiene revueltas laborales, y no hace nada m\u00e1s que ganar pasta, porque encima, y que yo sepa, hacienda tampoco les controla nada, y es m\u00e1s, en la declaraci\u00f3n de la renta que todos los pringaos de este pa\u00eds tenemos que hacer \u00bfno hab\u00eda una casillita de \u00abdonar a la iglesia cat\u00f3lica\u00bb? \u00a1Y una mierda! Antes me lo gasto en condones, pa que se jodan.<br \/>Como mi jefe caiga en la cuenta aqu\u00ed se va a armar la marimorena y nos van a endosar un h\u00e1bito, que lo veo yo venir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Que discutiendo de otras cosas con mi jefe estaba pensando en la religion cat\u00f3lica, todo esto a cuenta de que mi jefe dice que en esta empresa es Dios.Y uno, pues se da cuenta de que los cat\u00f3licos se lo tienen montao de miedo. Manejan al personal que ya le gustar\u00eda a mi jefe hacerlo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/17\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=17"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=17"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}