{"id":168,"date":"2008-02-27T11:17:58","date_gmt":"2008-02-27T10:17:58","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=168"},"modified":"2008-02-27T11:17:58","modified_gmt":"2008-02-27T10:17:58","slug":"yo-tambien-hablo-de-la-huelga","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2008\/02\/27\/yo-tambien-hablo-de-la-huelga\/","title":{"rendered":"Yo tambi\u00e9n hablo de la huelga"},"content":{"rendered":"<p>De la huelga de los cojones. Y mira que me dice la Chuchi que no me meta en pol\u00edtica que la cago. En fin&#8230;<\/p>\n<p>Vamos a ver si lo he entendido. Alguien est\u00e1 planteando montar una huelga para reclamar un colegio de inform\u00e1ticos para los ingenieros idem que regule responsabilidades, salarios y otras zarandajas. \u00bfEs eso? \u00bfSi?<\/p>\n<p>Vale, ahora voy a pon\u00e9rselo f\u00e1cil a los que me quieran criticar: NO SOY INGENIERO. \u00a1OH!<\/p>\n<p>Un colegio de ingenieros inform\u00e1ticos me parece una solemne gilipollez porque esta puta profesi\u00f3n no se puede comparar a las profesiones que s\u00ed tienen colegiados de esos. \u00bfPor qu\u00e9? Porque aqu\u00ed no vale con estar 2 a\u00f1os de becarios, 3 de interno o 5 de afilal\u00e1pices. Se\u00f1ores, esto cambia d\u00eda a d\u00eda. Y lo que hoy es blanco y est\u00e1 meridianamente claro, ma\u00f1ana te jodes y tiene motitas rojas.<\/p>\n<p>Sin desmerecer a los m\u00e9dicos, cuyo trabajo admiro y a los que doy much\u00edsimo curro, el cuerpo humano es finito, y sopena que te dediques a la investigaci\u00f3n, lo m\u00e1s nuevo que ven en a\u00f1os son brotes raros de gripe. Ahora dile a un ingeniero que en dos a\u00f1os no se va a comer ning\u00fan marr\u00f3n para el que no tiene ni documentaci\u00f3n ni herramientas y que lo va a tener que hacer todo nuevo. \u00bfOs imagin\u00e1is a un m\u00e9dico de cabecera desarrollando f\u00e1rmacos nuevos en su consulta? No, \u00bfverdad? \u00a1Pero est\u00e1n colegiados!<\/p>\n<p>\u00bfY? \u00bfQu\u00e9 les garantiza eso? Que tienen su responsabilidad regulada, como la tiene un arquitecto, por ejemplo. Que para hacerte la casa te tiene que firmar los planos un arquitecto y que por la firma te va a cobrar un coj\u00f3n de mico. Chachi. No digo yo que no me atraiga la idea de cobrar 12.000\u20ac por firmar un an\u00e1lisis de un programa, que lo realicen cuatro pelagatos salt\u00e1ndose las especificaciones, adpt\u00e1ndolo a nuevas exigencias y haciendo lo que surja y como se pueda.<\/p>\n<p>Porque volvemos a lo mismo, un edificio se construye con materiales X seg\u00fan los planos. Y ya est\u00e1. No quiero parecer d\u00e9spota ni mucho menos. S\u00e9 que voy a perder lectores, pero chico, o lo digo o reviento. Un edificio es algo concreto y finito. Si el arquitecto se lo curra puede calcular en una tarde hasta los ladrillos exactos que necesita. Ahora volvamos al programa de antes. \u00bfEl dise\u00f1ador o el analista o quien cojones sea que est\u00e9 colegiado va a decir si el ordenamiento de los registros se har\u00e1 por el m\u00e9todo de la burbuja o el de la baraja? \u00bfLe dir\u00e1 el nombre de las variables al programador y el tipo de datos? \u00bfLimitar\u00e1 el ingeniero el n\u00famero de variables que tiene que usar? \u00bfLe pondr\u00e1 un m\u00ednimo?<\/p>\n<p>Suena absurdo porque es absurdo. En esto de la inform\u00e1tica hay m\u00e1s de arte que de ciencia porque al ser un oficio tan nuevo, quien m\u00e1s quien menos tiene que investigar en diversas \u00e1reas. No vale con limitarse a lo que ya hay hecho. Mil veces tendremos problemas irresolutos y tendremos que enfrentarnos a ellos. Y ahora que venga una horda de ingenieros a decirme que hay que ser de la clase ingenieril para resolver esos problemas, porque entonces yo podr\u00e9 decir libremente que mis cojones son claveles.<\/p>\n<p>Que me diga quien quiera que por ser ingeniero de sistemas montar\u00e1 redes mejor que un t\u00edo que lleva tirando redes desde el 81 sin ser ingeniero. O que el hijo de \u00e9ste t\u00edo, que dorm\u00eda abrazado a una crimpadora. O que un ingeniero pica c\u00f3digo de mejor calidad que un chaval de 15 a\u00f1os que desayuna huevos con web beacons. No me jod\u00e1is. Los arquitectos llevan siglos haciendo edificios, los cirujanos los llevan abriendo pe\u00f1a. \u00bfLa inform\u00e1tica est\u00e1 en pa\u00f1ales y queremos regular algo que es irregulable? \u00bfY s\u00f3lo para ingenieros? Venga ya.<\/p>\n<p>El que haya hecho la carrera completa con dos cojones y un palito, y sea bueno en la profesi\u00f3n tiene todo mi respeto. Tanto resperto como l\u00e1stima me produce el que ha hecho un CFGS y sea mediocre como \u00e9l solo.  Se\u00f1ores, la val\u00eda se ha de demostrary no s\u00f3lo con papeles. No vale llorar al se\u00f1or gobierno para que le de una palmadita en la espalda y le diga al empresario que eres ingeniero y que tienes derecho a tal y a cual. No. \u00bfQu\u00e9 pasa? \u00bfNo hay huevos a empezar desde abajo? \u00bfComo eres ingeniero no te sale de los cojones mancharte de polvo la camisa desmontando cacharros? \u00bfNo quieres cargar con ordenadores arriba y abajo? \u00bfNo quieres pegarte una pech\u00e1 de picar c\u00f3digo como un cabr\u00f3n por cuatro perras como hacen los del CFGS de DAI? Ah, no, porque eres ingeniero de t\u00edtulo y sabes COBOL. No me toques los huevos con el t\u00edtulo enrollao, por favor.<\/p>\n<p>\u00bfQuer\u00e9is hacer una huelga para reclamar mejoras salariales? Yo me apunto el primero porque el salario medio es una puta mierda. \u00bfQuer\u00e9is que se regule la salubridad en el trabajo del inform\u00e1tico? Vamos a la huelga ya mismo a reclamar ambientes limpios y con luz natural y espacio suficiente para que el pedo de uno no se lo coman entre catorce. \u00bfQuer\u00e9is que vayamos a la huelga a reclamar indemnizaciones por enfermedades profesionales? \u00a1Vamos todos a pedir para gafas!<\/p>\n<p>Pero yo no voy a ir a una huelga  para pedir que mi firma valga dos millones porque soy honrado. No estudi\u00e9 ingenier\u00eda porque ni quise ni pude por temas de pasta y de que no me conced\u00edan becas. Pero me sacar\u00e9 la ingenier\u00eda en sistemas a ratos. Al fin y al cabo es estudiar, y eso lo llevo haciendo desde que me ense\u00f1aron a leer en casa. Yo no voy a llorarle al gobierno para que me garantice algo que yo no puedo garantizarle al empresario que me contrate.<\/p>\n<p>Estoy totalmente de acuerdo con <a href=\"http:\/\/www.eldiario.de\/bofh\/2008\/01\/31\/cuidadin-con-los-ingenieros\/\" title=\"M\u00e1s clarito que el agua.\">este se\u00f1or<\/a>,\u00a0 que dice verdades como pu\u00f1os y desde aqu\u00ed le mando mi apoyo.Mi respeto a los ingenieros sensatos de este pa\u00eds, que haberlos los hay y muy buenos. Pero hay \u00abingenieros\u00bb en sistemas que no saben ni hacer un ping. Y yo los he visto y he flipado porque no se cre\u00edan que la \u00fanica raz\u00f3n por la que el nodo A no conecta con el nodo B es porque no ten\u00edan direcciones IP del mismo rango. Y he ense\u00f1ado a programadores a usar componentes. Y se\u00f1ores, soy un puto FP llor\u00f3n. Pero intento hacer mi trabajo lo mejor posible y que me paguen por lo que hago y no por lo que soy.<\/p>\n<p>V\u00eda libre para que me apedreen.<\/p>\n<p>Edito para a\u00f1adir<a href=\"http:\/\/quotidiana.nydhosting.com\/?p=44\"> este otro link<\/a>, cuya opini\u00f3n me parece tambi\u00e9n muy acertada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la huelga de los cojones. Y mira que me dice la Chuchi que no me meta en pol\u00edtica que la cago. En fin&#8230; Vamos a ver si lo he entendido. Alguien est\u00e1 planteando montar una huelga para reclamar un colegio de inform\u00e1ticos para los ingenieros idem que regule responsabilidades, salarios y otras zarandajas. \u00bfEs [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-168","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=168"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/168\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}