{"id":134,"date":"2007-11-14T16:23:00","date_gmt":"2007-11-14T16:23:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=134"},"modified":"2007-11-14T16:23:00","modified_gmt":"2007-11-14T16:23:00","slug":"efectos-colaterales-del-agua","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2007\/11\/14\/efectos-colaterales-del-agua\/","title":{"rendered":"Efectos colaterales del agua."},"content":{"rendered":"<p>Esta ma\u00f1ana le he dicho a Miniyo que fuese a por el ordenador de Pollamboca para cambiarle el sistema operativo. Hasta ah\u00ed todo bien.<\/p>\n<p>Se lo ha traido a la cuadra que tenemos por despaho y le ha instalado el sistema operativo, despu\u00e9s se le une al dominio y se le configuran las cuentas para que todo vaya finito. Hasta ah\u00ed todo bien.<\/p>\n<p>El caso es que he estado un poco liadillo con otras historias m\u00e1s importantes que el hecho de que \u00e9sta est\u00e9 trabajando en otro ordenador.<\/p>\n<p>Pues ya por la tarde, o sea, hace un ratito, estaba realmente trabajando con su equipo. Estaba precisamente instal\u00e1ndole la cola de impresi\u00f3n para UNIX cuando me llama Pollamboca.<\/p>\n<p>-Sistemas&#8230;<br \/>-\u00a1Perdona, Wlardog!\u00a1Perdlona!<\/p>\n<p>\u00bfY a \u00e9sta qu\u00e9 cojones le pasa? Ser\u00e9 sutil.<\/p>\n<p>-\u00bfCohoneh te paha, tia?<br \/>-Esh que he apaglado mi plantalla shin qulerer.<\/p>\n<p>\u00bfDoing?<\/p>\n<p>-\u00bfQu\u00e9?<br \/>-Que.. \u00bfNo te aflectla?<br \/>-\u00bfQue apagues tu pantalla? Por m\u00ed como si le pegas fuego.<br \/>-Ah, no shle, como eshtas con lo del sishtema oplerativlo eshe que me tienesh que cambliar&#8230;<\/p>\n<p>Si cuando yo digo que esto es cosa del agua, es que es cosa del agua. O eso, o que, secretamente, entre ellos est\u00e1n compinchados a ver qui\u00e9n dice la burrada m\u00e1s grande.<\/p>\n<p>De hecho, no s\u00e9 de qu\u00e9 me sorprendo. Esto est\u00e1 extra\u00eddo del diccionario <a href=\"http:\/\/mundowdg.blogspot.com\/2007\/09\/diccionario-luser-cristiano.html\">Luser-Cristiano<\/a>:<\/p>\n<p class=\"MsoNormal\">\u00abTorre (CPU): Cosa   que hace ruido y esta calentita, perif\u00e9rico no necesariamente imprescindible.\u00bb<\/p>\n<p>Cagonlaputadoros&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana le he dicho a Miniyo que fuese a por el ordenador de Pollamboca para cambiarle el sistema operativo. Hasta ah\u00ed todo bien. Se lo ha traido a la cuadra que tenemos por despaho y le ha instalado el sistema operativo, despu\u00e9s se le une al dominio y se le configuran las cuentas para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-134","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=134"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/134\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}