{"id":113,"date":"2007-07-30T14:35:00","date_gmt":"2007-07-30T14:35:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=113"},"modified":"2007-07-30T14:35:00","modified_gmt":"2007-07-30T14:35:00","slug":"el-mundo-real","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2007\/07\/30\/el-mundo-real\/","title":{"rendered":"El mundo real."},"content":{"rendered":"<p>A\u00f1o 2018, Megacorp Software.<br \/>-Buenas tardes, $BOFH<br \/>-Buenas tardes, se\u00f1or presidente.<br \/>-Me han dicho que ha desarrollado usted un sistema de realidad virtual para el trabajo en la empresa.<br \/>-As\u00ed es, d\u00e9jeme que le explique. El sistema de realidad virtual facilita y agiliza el trabajo de la oficina porque suple el conocimiento del usuario de t\u00e9rminos y procedimientos inform\u00e1ticos para centrarse en el trabajo real del mismo. Es decir, si alguien debe introducir pedidos, por ejemplo, lo har\u00e1 usando la interfaz virtual, anotar\u00e1 el pedido en una hoja y el sistema se preocupa de aplicar la tarifa, corregir errores obvios, comprobar riesgos y tramitar el pedido. Si hay que hacer una factura, el administrativo en cuesti\u00f3n, s\u00f3lo tiene que buscar el albar\u00e1n en el archivador virtual, que encima tiene funciones de b\u00fasqueda autom\u00e1tica por voz, y tirar el albar\u00e1n en el buz\u00f3n de hacer facturas. El buz\u00f3n genera la factura, la env\u00eda al cliente, etc.<br \/>-Parece que tiene buena pinta.<br \/>-S\u00ed se\u00f1or, el sistema est\u00e1 teniendo una aceptaci\u00f3n bastante buena. Pero a\u00fan no est\u00e1 preparado.<br \/>-\u00bfNo? Yo lo veo bastante completo.<br \/>-No, a\u00fan no se puede vender. Mire lo que ocurre en una de las empresas que han probado la beta.<br \/>El $BOFH pulsa un bot\u00f3n en su ordenador y se ve una simulaci\u00f3n virtual de un entorno de trabajo.<br \/>-V\u00e9alo usted mismo.<br \/>-\u00a1Dios mio!\u00bfQu\u00e9 hacen esos locos?<br \/>Se ve a Bolindre , ayudado por Lucy arrastrando el archivador virtual por el suelo hasta el buz\u00f3n de facturar. Luego, con ayuda de la grapadora, hace palanca en el buz\u00f3n para abrirle m\u00e1s la boca y despu\u00e9s vierten el contenido del archivador en el buz\u00f3n.<br \/>-Pues eso no es nada. Mire, mire.<br \/>Pulsa otro bot\u00f3n y la pantalla cambia a una sala con tel\u00e9fono, una mesa, hojas de pedido y un bol\u00edgrafo. Es la sala donde se reciben los pedidos. De repente se materializa Pollamboca.<br \/>\u00ab\u00a1Josdher!\u00bb dice, y desaparece.<br \/>Se vuelve a materializar.<br \/>\u00ab\u00a1Eshto esh una mierdla!\u00a1Wardlog!\u00bb<br \/>Un BOFH se materializa a su lado.<br \/>\u00ab\u00bfQu\u00e9 pasa?\u00bb<br \/>\u00abEshto es una mierdla. \u00a1Yo muevo las manosh y aqu\u00ed no pasha nada!\u00bb<br \/>\u00abEspera\u00bb<br \/>El BOFH desaparece y deja a Pollamboca mirando al vac\u00edo. Al poco, Pollamboca empieza a pegarse guantazos a s\u00ed misma, descontrolada. Se mete los dedos en el ojo y se pinta la cara con el bol\u00edgrafo.<\/p>\n<p>-\u00bfQu\u00e9 le pasa a esta, $BOFH?<br \/>-Nada, el administrador de esa empresa le est\u00e1 \u00abrecordando\u00bb activamente que ha de ponerse los guantes de realidad virtual para actuar en el mundo ficticio.<br \/>-Joder, qu\u00e9 percal.<br \/>-Mire esto.<br \/>Cambia de pantalla y se ve a Lucky.<br \/>-\u00bfQu\u00e9 hace ese?<br \/>-Ese se\u00f1or se dedica a pagar a los proveedores.<br \/>-\u00bfC\u00f3mo lo hace?<br \/>-Mire. Por esa cinta van llegando las facturas que ha de pagar. \u00c9l apunta en un papelito los vencimientos de las facturas y los grapa. Luego, cuando tiene unos pocos, decide por qu\u00e9 banco paga y lo pone en el buz\u00f3n correspondiente. En el calendario, pulsando un d\u00eda con el dedo le avisa de los pagos que vencen ese d\u00eda. Si pulsa dos d\u00edas le avisa de los pagos que vencen en el periodo.<br \/>-Parece un proceso sencillo.<br \/>-Lo es, pero mire.<br \/>Se ve a Lucky materializ\u00e1ndose en la habitaci\u00f3n. Pero con los pies en el techo.<br \/>\u00ab\u00a1Wardog!\u00a1Mira lo que me pasa!\u00bb<br \/>El BOFH se materializa debajo de Lucky. Hace un gesto de disgusto y desaparece. Un segundo despu\u00e9s aparece Lucky del derecho y frot\u00e1ndose la cabeza.<br \/>-No me diga, $BOFH, el sysadmin le ha colocado las gafas de VR del derecho.<br \/>-Exacto. Siga mirando.<br \/>Se ve a Lucky contra la pared. Intenta caminar. Desaparece. Vuelve a aparecer. Intenta caminar contra la pared.<br \/>\u00ab\u00a1\u00a1Wardog!!\u00a1\u00a1Mira lo que me pasa!!\u00bb<br \/>\u00ab\u00bfQu\u00e9 co\u00f1o haces?\u00bb<br \/>\u00ab\u00a1Esto no funciona!\u00a1Quiero ir hacia el fichero y s\u00f3lo veo una pared que me corta el paso!\u00a1Esto est\u00e1 mal!\u00a1Pide que te lo cambien!\u00bb<br \/>Wardog desaparece y un segundo despu\u00e9s, Lucky se da la vuelta bruscamente y sale disparado en direcci\u00f3n contraria hasta chocar contra la pared.<br \/>\u00ab\u00a1GIRA!\u00a1CUANDO LLEGUES AL FINAL DE UNA HABITACION, GIRA!\u00a1NO ES TAN DIF\u00cdCIL!\u00a1EN LA VIDA REAL LO HACES! \u00bfNO?\u00bb<br \/>\u00abVale, vale, lo tendr\u00e9 que hacer as\u00ed, si no hay m\u00e1s remedio&#8230;\u00bb<br \/>-\u00a1Dios santo!<br \/>-Pues eso no es nada. En el almac\u00e9n hemos puesto robots, y los operarios s\u00f3lo se deben preocupar de buscar los art\u00edculos, consultando al or\u00e1culo virtual y moverlos. El peso no les afecta, pueden volar, atravesar muros&#8230;<br \/>-Y todo eso se refleja en acciones de los robots, \u00bfverdad?<br \/>-Exacto, los robots almacenan una cola de trabajo bastante compleja en la que se almacenan todos los movimientos que han ido indicando los operarios.<br \/>-\u00bfY cu\u00e1l es el problema?<br \/>-Que la cola siempre est\u00e1 vac\u00eda.<br \/>-\u00bfVac\u00eda?<br \/>-Bueno, no exactamente. Los robots no paran. Pero s\u00f3lo se hace un movimiento diario por operario. Luego se pierden y son incapaces de encontrar al or\u00e1culo.<br \/>-Estar\u00e1n jugando.<br \/>-Negativo. Como contramedida a situaciones de ocio por la flexibilidad de movimiento, se producen descargas el\u00e9ctricas cada vez que se detecta comportamiento l\u00fadico.<br \/>-\u00bfY funciona?<br \/>-S\u00ed, funciona. Trece accidentes laborales por electrocuci\u00f3n.<br \/>-\u00a1Dios m\u00edo!\u00a1Qu\u00e9 locura!<br \/>-Los calambrazos son de doce voltios. En principio, inofensivos.<br \/>-\u00bfEntonces?<br \/>-Eran insistentes. MUY insistentes. Quemaduras de tercer grado.<br \/>-Santa Mar\u00eda&#8230; Hay que ser bestia.<br \/>-\u00bfY lo de que no encuentren al or\u00e1culo lo han solucionado?<br \/>-M\u00e1s o menos&#8230; les pusimos un visor en las gafas de realidad virtual con una especie de \u00abGPS\u00bb, un sistema que mediante una flecha, indica la ubicaci\u00f3n del or\u00e1culo.<br \/>-\u00bfY funciona?<br \/>-No. Mire.<br \/>Conecta la pantalla correspondiente y se observa algo incre\u00edble. Ocho operarios dando vueltas alrededor del or\u00e1culo y blasfemando.<br \/>\u00ab\u00a1Puto or\u00e1culo!\u00a1Ya lo han vuelto a mover!\u00bb<br \/>\u00ab\u00a1Pero d\u00f3nde est\u00e1!\u00bb<br \/>\u00ab\u00a1Hala!\u00a1Otra vez ocho horas dando vueltas por la puta flechita!\u00bb<br \/>-Incre\u00edble. \u00bfQu\u00e9 empresa es esta?<br \/>-Killminds, se\u00f1or.<br \/>-Bien. D\u00edgales que el producto no satisface sus necesidades y que muchas gracias por su colaboraci\u00f3n.<br \/>-De acuerdo, se\u00f1or.<br \/>-Acto seguido, p\u00f3ngalo a la venta.<br \/>-\u00bfPerd\u00f3n? No dec\u00eda que no&#8230;<br \/>-Las personas normales lo har\u00e1n bien. En agradecimiento, mande a Killminds un ej\u00e9rcito de educadores especiales. Y a ese sysadmin m\u00e1ndele un jam\u00f3n, pobrecillo.<\/p>\n<p>Moraleja: Cambiar una aplicaci\u00f3n para facilitar las tareas al personal es in\u00fatil. Un idiota con herramientas de alta tecnolog\u00eda produce cagadas de alta tecnolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A\u00f1o 2018, Megacorp Software.-Buenas tardes, $BOFH-Buenas tardes, se\u00f1or presidente.-Me han dicho que ha desarrollado usted un sistema de realidad virtual para el trabajo en la empresa.-As\u00ed es, d\u00e9jeme que le explique. El sistema de realidad virtual facilita y agiliza el trabajo de la oficina porque suple el conocimiento del usuario de t\u00e9rminos y procedimientos inform\u00e1ticos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-113","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=113"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/113\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}