{"id":11,"date":"2005-10-07T15:40:00","date_gmt":"2005-10-07T15:40:00","guid":{"rendered":"http:\/\/www.mundowdg.com\/blog\/?p=11"},"modified":"2005-10-07T15:40:00","modified_gmt":"2005-10-07T15:40:00","slug":"trufo","status":"publish","type":"post","link":"https:\/\/mundowdg.com\/blog\/2005\/10\/07\/trufo\/","title":{"rendered":"Trufo"},"content":{"rendered":"<p>Cuando empec\u00e9 a salir con Chuchi, Trufo ven\u00eda en el lote. Es un <a href=\"http:\/\/www.ozpets.com.au\/dogs\/review\/media\/germanspitz\/germanspitz03.jpg\">spitz alem\u00e1n mediano de color blanco. <\/a><br \/>El perro es la leche de inteligente. Le pides lapelota y te la trae para jugar. Si se lleva un hueso o un coscurro de pan al sal\u00f3n le dices que se lo lleve al patio y el animalito se levanta, lo coge y se va. No sube al sof\u00e1 si no se lo dices. Hablar le falta al animalito.<br \/>Pero hemos descubierto que a Trufo no le gustan los ordenadores. De ning\u00fan tipo, adem\u00e1s. Es autom\u00e1tico. Si Chuchi enciende el pc del sal\u00f3n, all\u00e1 que te va Trufo a darle a Chuchi con la patita para que deje de enredar con el ordenador y juegue con \u00e9l. El cuanto Chuchi apaga el ordenador el perro pasa de ella.<br \/>Anoche estaba revisando c\u00f3digo con el port\u00e1til, espanzurrao en el sof\u00e1. El perro se subi\u00f3 y con su patita derecha se lio a hostia limpia con el teclado.<br \/>Le rega\u00f1o y le digo que se baje del sof\u00e1. Me siento y pongo el port\u00e1til en la mesita. El perro que vuelve. Me mira. Le miro.<br \/>-Como vuelvas a patear el ordenador te rapo.<br \/>Trufo me mira con media lengua fuera de su boca cerrada y tuerce la cabeza hacia la derecha como hace siempre que trama algo. Se sube al sof\u00e1. Me mira. Sigo con el port\u00e1til. Se acerca a m\u00ed. Se tumba y se mete reptando entre mis piernas y mis brazos, se gira, me mira, abre la boca, se le cae la lengua y me da una hostia con la pata en la cara para quedarse mirando con esos ojitos chispeantes que tiene el muy cabr\u00f3n.<br \/>A ver qui\u00e9n de vosotros tiene un perro que adem\u00e1s de dar la patita, sea tan cabr\u00f3n que se salga siempre con la suya y encima te haga descojonarte.<br \/><a href=\"http:\/\/www.mundosdenepomuk.blogspot.com\">Nepomuk<\/a>, tu perro no vale porque es idiota \ud83d\ude42<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando empec\u00e9 a salir con Chuchi, Trufo ven\u00eda en el lote. Es un spitz alem\u00e1n mediano de color blanco. El perro es la leche de inteligente. Le pides lapelota y te la trae para jugar. Si se lleva un hueso o un coscurro de pan al sal\u00f3n le dices que se lo lleve al patio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-11","post","type-post","status-publish","format-standard","hentry","category-general"],"_links":{"self":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/comments?post=11"}],"version-history":[{"count":0,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/posts\/11\/revisions"}],"wp:attachment":[{"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/media?parent=11"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/categories?post=11"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundowdg.com\/blog\/wp-json\/wp\/v2\/tags?post=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}